{"id":1801,"date":"2025-07-17T15:53:28","date_gmt":"2025-07-17T20:53:28","guid":{"rendered":"https:\/\/uwacafe.com\/subscriptions\/"},"modified":"2026-02-04T15:42:23","modified_gmt":"2026-02-04T20:42:23","slug":"subscriptions","status":"publish","type":"page","link":"https:\/\/uwa.sapiens-lab.com\/en\/subscriptions\/","title":{"rendered":"Subscriptions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1801\" class=\"elementor elementor-1801 elementor-1403\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d69bea e-con-full e-flex e-con e-parent\" data-id=\"5d69bea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0101e03 elementor-widget elementor-widget-heading\" data-id=\"0101e03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CAFFEINE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36c17ed elementor-widget elementor-widget-heading\" data-id=\"36c17ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Curated for you<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4854e0a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4854e0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c951d5f e-con-full e-flex e-con e-parent\" data-id=\"c951d5f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fc37738 e-con-full e-flex e-con e-child\" data-id=\"fc37738\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fe81d19 elementor-hidden-mobile elementor-invisible elementor-widget elementor-widget-image\" data-id=\"fe81d19\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1709\" height=\"2560\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled.png\" class=\"attachment-full size-full wp-image-1407\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled.png 1709w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled-300x449.png 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-200x300.png 200w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-684x1024.png 684w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-768x1150.png 768w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-1026x1536.png 1026w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-1367x2048.png 1367w\" sizes=\"(max-width: 1709px) 100vw, 1709px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b626c96 e-con-full e-flex e-con e-child\" data-id=\"b626c96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecd6119 elementor-widget elementor-widget-text-editor\" data-id=\"ecd6119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tTravel to Colombia, One Cup at a Time!\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86300ab elementor-widget elementor-widget-text-editor\" data-id=\"86300ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>&#8220;Immerse yourself each month in the vibrant world of Colombian specialty coffee with our renewable 3-month subscriptions, designed for lovers of flavor, discovery, and authenticity.<\/p><p>Each plan includes a selection of exceptional coffees, shipping included, and, depending on the chosen option, exclusive gifts.<\/p><p>Subscribe today and let the magic of U\u2019WA coffee transform your everyday life.!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aac6baa e-con-full e-flex e-con e-parent\" data-id=\"aac6baa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f232b78 e-con-full e-flex e-con e-child\" data-id=\"f232b78\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12d2754 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"12d2754\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mariposa_Roja.png\" class=\"attachment-full size-full wp-image-1425\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mariposa_Roja.png 500w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mariposa_Roja-300x300.png 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mariposa_Roja-100x100.png 100w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mariposa_Roja-150x150.png 150w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mariposa_Roja-50x50.png 50w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13528cb elementor-widget elementor-widget-heading\" data-id=\"13528cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The diversity of Colombia in<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e7346a elementor-widget elementor-widget-heading\" data-id=\"8e7346a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">a cup of coffee<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0280a17 e-con-full e-flex e-con e-parent\" data-id=\"0280a17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-31c6e1c e-con-full e-flex e-con e-child\" data-id=\"31c6e1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e94d87 elementor-widget elementor-widget-image\" data-id=\"6e94d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"620\" height=\"700\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_1.jpg\" class=\"attachment-full size-full wp-image-1370\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_1.jpg 620w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_1-300x339.jpg 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_1-266x300.jpg 266w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-121cc27 e-con-full e-flex e-con e-child\" data-id=\"121cc27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7d7029 elementor-widget elementor-widget-heading\" data-id=\"d7d7029\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rio U'WA SUBSCRIPTION 33\u20ac \/ Month<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0837eb6 elementor-widget elementor-widget-heading\" data-id=\"0837eb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Smooth discovery<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec748e6 e-con-full e-flex e-con e-child\" data-id=\"ec748e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec4863c elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ec4863c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-d61e559f-1076-49ef-8fc4-eb97ee1c5c42\" viewBox=\"0 0 33.65 50\"><path d=\"M.52,50c-.77-.07-.57-1.37-.15-1.37h1.81c-.07-.15-.1-.27-.1-.43-.23-9.17.18-18.37,0-27.54l3.88-13.31c.17-2.15-.17-4.48.02-6.62.03-.28.04-.51.32-.66L26.94,0c.39,0,.66.15.72.55.13.81,0,2.14,0,3.02,0,1.31-.13,2.99.13,4.26.86,4.19,2.85,8.59,3.78,12.82-.18,9.17.23,18.37,0,27.54,0,.17-.03.29-.1.43h1.81c.42,0,.62,1.3-.15,1.37H.52ZM11.26,1.37h-4v2.05h4V1.37ZM20.93,1.37h-8.2v10.4c0,1.7,2.46,3.38,4.05,3.38s4.15-1.64,4.15-3.38V1.37ZM26.3,1.37h-3.91v2.05h3.91V1.37ZM11.26,4.79h-3.86l-.15.15v1.86l.15.15h3.86v-2.15ZM26.3,4.79h-3.91v2.15h3.91v-2.15ZM11.26,8.3h-4.05l-3.47,11.62h13.52c.8,0,.69,1.37.1,1.37H3.45v27.1s.15.17.2.19l26.12.06c.36.02.44-.35.44-.64v-27.05s-3.76-12.65-3.76-12.65h-4.05v2.78c0,1.22-.8,2.94-1.67,3.8-3.16,3.12-8.47,1.43-9.32-2.87l-.14-1.03v-2.69Z\"><\/path><path d=\"M16.22,24.35c8.36-.47,14.06,8.63,9.9,15.95-4.08,7.18-14.56,7.23-18.59,0s.81-15.51,8.69-15.95ZM16.41,25.72c-6.92.3-11.14,7.86-7.71,13.9s12.7,6.29,16.24,0c3.59-6.38-1.25-14.22-8.53-13.9Z\"><\/path><path d=\"M18.26,11.56c.43.35.21,1.1-.33,1.22-.31.07-1.89.07-2.2,0-.66-.15-.79-1.17-.1-1.33.35-.08,2.42-.07,2.64.11Z\"><\/path><path d=\"M18.17,28.64c2.14-.24,4.18.51,4.88,2.69,2,6.3-8.91,13.95-12.13,8.13-2.34-4.23,2.98-10.33,7.25-10.81ZM19.66,29.98h-1.51c-.73,0-2.71,1.16-3.32,1.66-2.04,1.69-4.59,5.68-2.01,7.91.13-1.06.49-2.13,1.22-2.93,1.34-1.46,3.42-1.83,4.58-3.52.6-.88,1.02-2.05,1.03-3.12ZM14.09,40.03c1.16.26,2.5-.25,3.51-.82,1.78-1.01,3.5-2.94,4.05-4.93.36-1.3.4-2.58-.59-3.61-.56,2.27-1.39,3.83-3.38,5.12-1.78,1.15-3.49,1.7-3.6,4.25Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b92ec1 elementor-widget elementor-widget-heading\" data-id=\"0b92ec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">500g of specialty coffee<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e14276 e-con-full e-flex e-con e-child\" data-id=\"3e14276\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb08344 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cb08344\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-63625bcd-a9b6-47ce-9234-c0f7dc82e297\" viewBox=\"0 0 50 44.88\"><path d=\"M.03,30.13c-.04-.3-.03-.97,0-1.27.54-4.68,6.88-4.22,6.74.74-.13,4.79-6.18,4.96-6.74.53ZM4.13,32.19c2.26-1.1,2.08-4.78-.35-5.55-1.27,1.67.41,3.02.44,4.63,0,.27-.18.62-.1.93ZM2.47,26.91c-.17-.18-1.03.98-1.12,1.17-.67,1.47-.11,3.7,1.56,4.2.81-1.39-.5-2.45-.62-3.77-.06-.6.06-1.03.18-1.6Z\"><\/path><path d=\"M13.69,25.06c-2.85-1.03-2.56-4.43-.24-5.97,1.27-.84,3.26-1.05,4.54-.14.18.13.56.64.72.62.66-.56,1.74-.76,2.4-1.21,1.18-.81,2.39-2.7,3.57-3.56,1.09-.78,2.24-.37,3.04.57.89-.51,1.53-.78,2.51-.26.34.18.48.49.79.66.71-.72,1.47-1.4,2.16-2.14,3.62-3.88,6.9-8.27,10.54-12.11.48-.51.97-1.05,1.64-1.29,3.37-1.21,6.06,2.62,3.83,5.39-3.99,3.67-8.25,7.04-12.25,10.69-.95.87-1.92,1.74-2.73,2.74,1.44,1.18,1.77,2.66.53,4.15-6.76,6.38-13.02,13.53-19.82,19.83-1.52,1.41-2.88,2.69-4.96,1.15-1.21-.89-1.13-1.7-1.58-2.91-1.4-3.76-1.8-6.76.5-10.35,1.09-1.71,4.33-4.06,4.78-5.58.03-.09.08-.18.04-.29ZM46.28,1.05c-.79.11-1.27.6-1.78,1.14-3.46,3.66-6.57,7.86-10.05,11.53l-.11.29,1.74,1.65,12.45-10.89c1.17-1.73-.18-4.01-2.25-3.72ZM33.56,14.7l-1.8,1.81,1.71,1.71,1.8-1.72-1.7-1.79ZM23.16,17.92l2.44-.25,1.36-1.55c-.24-.31-.68-.74-1.1-.72-.75.04-2.14,1.96-2.7,2.51ZM17.9,38.33l.33-.08,15.98-16.05c.31-.55.38-1.07.02-1.63l-4.66-4.62c-.41-.2-.83,0-1.15.27-3.14,3.42-6.87,6.52-9.96,9.96-3.27,3.64-3.61,8.22-.57,12.15ZM24.33,18.81c-1.36.06-2.84.46-4.07,1.06-.25.12-1.07.51-1.11.75-.03.19.11.58.11.88-.02,2.24-2.37,3.9-4.48,3.87-.39.86-.71,1.76-.86,2.7-.24,1.4,0,2.75-.81,3.98-.27.41-.69.71-.9,1.15-.52,1.11-.17,2.62-.28,3.82,2.05.28,3.29,2.27,3.23,4.26l2.14-2.11c-3.37-4.05-3.32-9.45.15-13.42l6.88-6.93ZM17.6,20.07c-1.95-1.75-5.31.17-4.88,2.74.56-.03,1.24-.08,1.73-.37.62-.37.92-1.07,1.4-1.53.45-.43,1.13-.76,1.75-.84ZM18.18,20.95c-1.69.1-2.03,1.65-3.29,2.42l-1.4.5c2.07,1.16,5.01-.46,4.68-2.93ZM10.85,37.16c.1-1.47-.24-3.2.48-4.55.34-.63.94-1.01,1.19-1.74.3-.87.13-1.8.29-2.69-3.35,2.69-5.38,6.57-4.2,10.94.57-.81,1.2-1.74,2.23-1.96ZM12.72,43.52c.17.04.2-.07.29-.15,1.9-1.45,1.22-4.87-1.17-5.32-.09.57-.34,1-.28,1.6.09.91.74,1.41.99,2.23.17.56.2,1.05.17,1.64ZM11.64,43.71v-1.42c0-.36-1.07-1.62-1.07-2.15v-1.47s.27-.26-.05-.24c-1.85,1.4-1.3,5,1.12,5.27Z\"><\/path><path d=\"M4.5,15.8c4.94-.22,5.57,6.14.84,6.7-5.52.65-6.08-6.47-.84-6.7ZM5.74,18.41c.39-.06,1.03,0,1.46,0,.02,0,.12.15.24.1-.97-2.33-4.87-2.24-5.55.24.47.42,1.27.52,1.89.45.68-.08,1.35-.69,1.95-.78ZM7.54,19.59c-1.93-.8-3.26,1.41-5.24.5-.12-.06-.18.03-.13.13.08.18.61.66.79.78,1.5.98,4.05.46,4.58-1.41Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99bc94d elementor-widget elementor-widget-heading\" data-id=\"99bc94d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Freshly roasted coffee<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-093ae6d e-con-full e-flex e-con e-child\" data-id=\"093ae6d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e03a582 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e03a582\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-c8ebb19a-8a85-48f0-a3d2-bbd278f6e9bc\" viewBox=\"0 0 50 30.81\"><path d=\"M0,12.87v-.49c.2-.25.37-.49.73-.49l13.99.05c.82.52.43,1.55-.54,1.52H.83c-.4,0-.6-.32-.83-.59Z\"><\/path><path d=\"M35.27,5.36h9.11c.53,0,1.54.84,1.82,1.3l3.66,8.72c-.23,3.26.38,7.12.02,10.31-.24,2.11-2.54,1.84-4.09,1.81-.62,3.85-6.07,4.56-7.72,1.04-.17-.36-.17-1.05-.61-1.05h-15.58c-1.09,4.39-7.16,4.48-8.16.02-2.16-.28-6.46,1.03-6.81-2.2-.12-1.11-.13-3.97,0-5.07.11-.91,1.25-1,1.54-.17l.03,5.14c.12.49.43.7.92.74,1.37.13,2.94-.09,4.33-.02.99-4.4,7.1-4.4,8.1.01h11.89V2.19c0-.12-.51-.71-.73-.64H9.11c-1.32.26-.05,3.7-1.03,4.15-.5.23-1.07-.03-1.16-.59-.1-.6-.06-2.64.06-3.25.2-.98,1.05-1.74,2.03-1.87h24.16c.92.03,2.09,1.2,2.09,2.1v3.27ZM48.32,19.4l-.02-3.83c-1.23-2.45-2.04-5.41-3.3-7.81-.13-.24-.52-.84-.81-.84h-8.91v19.01h2.53c.81-4.42,7.17-4.4,7.99,0,.53-.08,1.98.16,2.37-.09.26-.17.13-.98.16-1.27h-1.41c-.43,0-1.02-.47-1.17-.88-.22-.6-.24-2.83-.02-3.43.1-.28.64-.85.9-.85h1.71ZM48.32,20.96h-1.17v1.9c.28.29.79.1,1.17.15v-2.05ZM17.32,24.2c-3.18.46-2.61,5.64,1.02,5.02,2.99-.51,2.5-5.53-1.02-5.02ZM41.28,24.2c-.96.15-1.89,1.11-2.01,2.08-.37,3.08,3.54,4.06,4.77,1.65.99-1.96-.62-4.08-2.76-3.73Z\"><\/path><path d=\"M18.68,7.63c.44.48.15,1.27-.5,1.34H4.53c-1.03-.12-1.13-1.44,0-1.57l13.81.03c.1.06.26.11.33.2Z\"><\/path><path d=\"M3.09,16.3l13.32-.02c1.04-.02,1.49,1.22.4,1.56H2.97c-1.05-.12-.87-1.5.13-1.54Z\"><\/path><path d=\"M36.47,8.12c.15-.17.38-.21.6-.23,1.55-.15,4.79-.14,6.34,0,.67.06.67.37.94.91.93,1.91,1.61,4.03,2.52,5.96.27.8-.04,1.15-.83,1.23-2.81.26-6.02-.21-8.87,0-.58-.01-.88-.38-.93-.93-.14-1.48-.16-4.89,0-6.34.02-.18.11-.47.23-.6ZM42.97,9.45h-5.16v4.97h7.21l-2.05-4.97Z\"><\/path><path d=\"M17.78,25.59c1.73,0,1.28,2.78-.39,2.2-1.19-.42-.85-2.2.39-2.2Z\"><\/path><path d=\"M41.76,25.57c1.23-.04,1.6,1.67.52,2.16-1.71.78-2.32-2.11-.52-2.16Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60ac971 elementor-widget elementor-widget-heading\" data-id=\"60ac971\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Delivery included<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c5879b e-con-full e-flex e-con e-child\" data-id=\"8c5879b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78e3158 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"78e3158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-a5b6178d-152f-4a33-bb18-edd466ea6210\" viewBox=\"0 0 49.58 49.6\"><path d=\"M49.52,34.92c-.05-1.63-.1-3.32-.01-4.96-.11-1.28-.77-2.4-1.81-3.07-1.02-.65-2.27-.78-3.45-.36-.08.03-.24.11-.48.25-.11.06-.26.14-.37.2-.29-.78-.87-1.44-1.64-1.85-.92-.5-2.03-.61-3.03-.3-.35.11-.63.29-.9.46-.15.1-.3.19-.45.27-.48-.78-1.29-1.35-2.25-1.59-.96-.23-1.94-.11-2.76.33v-5.15c2.99-1.34,5.2-4.36,5.64-7.74.35-2.71-.46-5.5-2.22-7.63-1.77-2.15-4.36-3.48-7.11-3.66-3.25-.21-6.68-.11-9.98-.02-3.04.08-6.19.17-9.22.02C4.69.36.46,4.4.02,9.13c-.03.35-.02.72,0,1.08.01.31.02.64,0,.93v.03s0,.03,0,.03c.08.29.13.58.19.87.07.37.15.76.26,1.13,1.25,3.95,4.94,6.75,9.18,6.97h14.89s0,8.27,0,8.27c-.39-.57-.76-1.25-1.14-1.95-1.25-2.32-2.66-4.95-5.7-4.2-1.07.26-1.95.92-2.47,1.86-.54.98-.64,2.18-.26,3.33,1.18,2.23,2.34,4.52,3.46,6.74,1.31,2.59,2.67,5.27,4.06,7.87l.11.21c1.68,3.16,2.9,5.44,6.6,6.72.63.22,1.25.34,1.9.47l.44.09h8.93c4.73-.44,8.69-4.54,9.01-9.34.12-1.74.06-3.57.01-5.34ZM32.35,16.83v-5.9c0-.39-.44-1.29-.55-1.49-.63-1.12-1.73-1.82-3.02-1.93-1.29-.11-2.55.42-3.36,1.42-.28.35-.86,1.45-.86,1.91v7.31h-14.69c-5.34-.31-7.73-4.24-7.74-7.98,0-3.62,2.36-7.67,7.54-7.99,1.41-.09,2.86-.12,4.31-.12,1.84,0,3.68.05,5.5.1,3,.08,6.1.16,9.05.02,3.6.27,6.44,2.7,7.25,6.19.77,3.34-.57,6.62-3.44,8.46ZM25.95,33.13c.39-.16.64-.55.66-1.03V11.16c.25-1.24,1.2-1.65,1.9-1.62.8.03,1.66.6,1.8,1.76v16.38c-.03.52.31.95.81,1.02,1.03.15,1.15-.59,1.25-1.13.03-.18.06-.37.12-.53.35-.94,1.25-1.19,1.91-1.12.64.07,1.44.49,1.56,1.41.02.13.02.3.02.48,0,.62,0,1.56.8,1.73,1.01.22,1.2-.63,1.35-1.25.07-.3.14-.62.29-.82.53-.75,1.35-.86,1.95-.7.59.15,1.26.63,1.35,1.51.02.16,0,.41,0,.67-.03.71-.07,1.6.39,2.02.21.19.49.26.83.21.65-.09.78-.68.9-1.2.09-.4.18-.81.47-1.1.51-.51,1.21-.67,1.88-.44.69.24,1.18.85,1.27,1.55-.05,1.21-.01,2.52.03,3.9.18,5.56.37,11.87-6.09,13.43-1.91.46-7.04.4-9.38.23-2.82-.2-5.12-1.72-6.64-4.39-1.48-2.61-2.85-5.38-4.18-8.06-1.32-2.67-2.68-5.43-4.16-8.02-.55-1.13-.09-2.08.62-2.53.29-.18.64-.29,1-.29.52,0,1.06.22,1.5.78l4.57,7.79.04.05c.35.33.79.43,1.18.27Z\"><\/path><path d=\"M22.01,5.9c-.18.04-.34.14-.48.3l-4.25,5.68s-.02-.01-.02-.02c-.11-.08-.25-.24-.39-.4-.24-.28-.49-.56-.76-.64-.43-.14-.84-.03-1.1.28-.28.33-.32.83-.1,1.25.09.18,1.78,1.86,1.96,1.96.18.1.36.14.53.14.31,0,.61-.16.87-.47l4.94-6.62c.18-.41.15-.83-.1-1.13-.25-.3-.66-.42-1.11-.33Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9122dcc elementor-widget elementor-widget-heading\" data-id=\"9122dcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Subscription: 3 months for \u20ac99<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94cdede elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"94cdede\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uwa.sapiens-lab.com\/en\/producto\/rio-uwa-suscription\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SUBSCRIBE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f95300 e-con-full e-flex e-con e-parent\" data-id=\"4f95300\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-34058d0 e-con-full e-flex e-con e-child\" data-id=\"34058d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96c1ffb elementor-widget elementor-widget-heading\" data-id=\"96c1ffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Monta\u00f1a sagrada Suscription 45\u20ac \/ Month<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-883b245 elementor-widget elementor-widget-heading\" data-id=\"883b245\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Perfect Balance<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92eb8d1 e-con-full e-flex e-con e-child\" data-id=\"92eb8d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef05cbe elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ef05cbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-d61e559f-1076-49ef-8fc4-eb97ee1c5c42\" viewBox=\"0 0 33.65 50\"><path d=\"M.52,50c-.77-.07-.57-1.37-.15-1.37h1.81c-.07-.15-.1-.27-.1-.43-.23-9.17.18-18.37,0-27.54l3.88-13.31c.17-2.15-.17-4.48.02-6.62.03-.28.04-.51.32-.66L26.94,0c.39,0,.66.15.72.55.13.81,0,2.14,0,3.02,0,1.31-.13,2.99.13,4.26.86,4.19,2.85,8.59,3.78,12.82-.18,9.17.23,18.37,0,27.54,0,.17-.03.29-.1.43h1.81c.42,0,.62,1.3-.15,1.37H.52ZM11.26,1.37h-4v2.05h4V1.37ZM20.93,1.37h-8.2v10.4c0,1.7,2.46,3.38,4.05,3.38s4.15-1.64,4.15-3.38V1.37ZM26.3,1.37h-3.91v2.05h3.91V1.37ZM11.26,4.79h-3.86l-.15.15v1.86l.15.15h3.86v-2.15ZM26.3,4.79h-3.91v2.15h3.91v-2.15ZM11.26,8.3h-4.05l-3.47,11.62h13.52c.8,0,.69,1.37.1,1.37H3.45v27.1s.15.17.2.19l26.12.06c.36.02.44-.35.44-.64v-27.05s-3.76-12.65-3.76-12.65h-4.05v2.78c0,1.22-.8,2.94-1.67,3.8-3.16,3.12-8.47,1.43-9.32-2.87l-.14-1.03v-2.69Z\"><\/path><path d=\"M16.22,24.35c8.36-.47,14.06,8.63,9.9,15.95-4.08,7.18-14.56,7.23-18.59,0s.81-15.51,8.69-15.95ZM16.41,25.72c-6.92.3-11.14,7.86-7.71,13.9s12.7,6.29,16.24,0c3.59-6.38-1.25-14.22-8.53-13.9Z\"><\/path><path d=\"M18.26,11.56c.43.35.21,1.1-.33,1.22-.31.07-1.89.07-2.2,0-.66-.15-.79-1.17-.1-1.33.35-.08,2.42-.07,2.64.11Z\"><\/path><path d=\"M18.17,28.64c2.14-.24,4.18.51,4.88,2.69,2,6.3-8.91,13.95-12.13,8.13-2.34-4.23,2.98-10.33,7.25-10.81ZM19.66,29.98h-1.51c-.73,0-2.71,1.16-3.32,1.66-2.04,1.69-4.59,5.68-2.01,7.91.13-1.06.49-2.13,1.22-2.93,1.34-1.46,3.42-1.83,4.58-3.52.6-.88,1.02-2.05,1.03-3.12ZM14.09,40.03c1.16.26,2.5-.25,3.51-.82,1.78-1.01,3.5-2.94,4.05-4.93.36-1.3.4-2.58-.59-3.61-.56,2.27-1.39,3.83-3.38,5.12-1.78,1.15-3.49,1.7-3.6,4.25Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-beeed7d elementor-widget elementor-widget-heading\" data-id=\"beeed7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">750g of specialty coffee<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f08eaba e-con-full e-flex e-con e-child\" data-id=\"f08eaba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f98a236 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f98a236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-63625bcd-a9b6-47ce-9234-c0f7dc82e297\" viewBox=\"0 0 50 44.88\"><path d=\"M.03,30.13c-.04-.3-.03-.97,0-1.27.54-4.68,6.88-4.22,6.74.74-.13,4.79-6.18,4.96-6.74.53ZM4.13,32.19c2.26-1.1,2.08-4.78-.35-5.55-1.27,1.67.41,3.02.44,4.63,0,.27-.18.62-.1.93ZM2.47,26.91c-.17-.18-1.03.98-1.12,1.17-.67,1.47-.11,3.7,1.56,4.2.81-1.39-.5-2.45-.62-3.77-.06-.6.06-1.03.18-1.6Z\"><\/path><path d=\"M13.69,25.06c-2.85-1.03-2.56-4.43-.24-5.97,1.27-.84,3.26-1.05,4.54-.14.18.13.56.64.72.62.66-.56,1.74-.76,2.4-1.21,1.18-.81,2.39-2.7,3.57-3.56,1.09-.78,2.24-.37,3.04.57.89-.51,1.53-.78,2.51-.26.34.18.48.49.79.66.71-.72,1.47-1.4,2.16-2.14,3.62-3.88,6.9-8.27,10.54-12.11.48-.51.97-1.05,1.64-1.29,3.37-1.21,6.06,2.62,3.83,5.39-3.99,3.67-8.25,7.04-12.25,10.69-.95.87-1.92,1.74-2.73,2.74,1.44,1.18,1.77,2.66.53,4.15-6.76,6.38-13.02,13.53-19.82,19.83-1.52,1.41-2.88,2.69-4.96,1.15-1.21-.89-1.13-1.7-1.58-2.91-1.4-3.76-1.8-6.76.5-10.35,1.09-1.71,4.33-4.06,4.78-5.58.03-.09.08-.18.04-.29ZM46.28,1.05c-.79.11-1.27.6-1.78,1.14-3.46,3.66-6.57,7.86-10.05,11.53l-.11.29,1.74,1.65,12.45-10.89c1.17-1.73-.18-4.01-2.25-3.72ZM33.56,14.7l-1.8,1.81,1.71,1.71,1.8-1.72-1.7-1.79ZM23.16,17.92l2.44-.25,1.36-1.55c-.24-.31-.68-.74-1.1-.72-.75.04-2.14,1.96-2.7,2.51ZM17.9,38.33l.33-.08,15.98-16.05c.31-.55.38-1.07.02-1.63l-4.66-4.62c-.41-.2-.83,0-1.15.27-3.14,3.42-6.87,6.52-9.96,9.96-3.27,3.64-3.61,8.22-.57,12.15ZM24.33,18.81c-1.36.06-2.84.46-4.07,1.06-.25.12-1.07.51-1.11.75-.03.19.11.58.11.88-.02,2.24-2.37,3.9-4.48,3.87-.39.86-.71,1.76-.86,2.7-.24,1.4,0,2.75-.81,3.98-.27.41-.69.71-.9,1.15-.52,1.11-.17,2.62-.28,3.82,2.05.28,3.29,2.27,3.23,4.26l2.14-2.11c-3.37-4.05-3.32-9.45.15-13.42l6.88-6.93ZM17.6,20.07c-1.95-1.75-5.31.17-4.88,2.74.56-.03,1.24-.08,1.73-.37.62-.37.92-1.07,1.4-1.53.45-.43,1.13-.76,1.75-.84ZM18.18,20.95c-1.69.1-2.03,1.65-3.29,2.42l-1.4.5c2.07,1.16,5.01-.46,4.68-2.93ZM10.85,37.16c.1-1.47-.24-3.2.48-4.55.34-.63.94-1.01,1.19-1.74.3-.87.13-1.8.29-2.69-3.35,2.69-5.38,6.57-4.2,10.94.57-.81,1.2-1.74,2.23-1.96ZM12.72,43.52c.17.04.2-.07.29-.15,1.9-1.45,1.22-4.87-1.17-5.32-.09.57-.34,1-.28,1.6.09.91.74,1.41.99,2.23.17.56.2,1.05.17,1.64ZM11.64,43.71v-1.42c0-.36-1.07-1.62-1.07-2.15v-1.47s.27-.26-.05-.24c-1.85,1.4-1.3,5,1.12,5.27Z\"><\/path><path d=\"M4.5,15.8c4.94-.22,5.57,6.14.84,6.7-5.52.65-6.08-6.47-.84-6.7ZM5.74,18.41c.39-.06,1.03,0,1.46,0,.02,0,.12.15.24.1-.97-2.33-4.87-2.24-5.55.24.47.42,1.27.52,1.89.45.68-.08,1.35-.69,1.95-.78ZM7.54,19.59c-1.93-.8-3.26,1.41-5.24.5-.12-.06-.18.03-.13.13.08.18.61.66.79.78,1.5.98,4.05.46,4.58-1.41Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e8185 elementor-widget elementor-widget-heading\" data-id=\"27e8185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Freshly roasted coffee<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1881f98 e-con-full e-flex e-con e-child\" data-id=\"1881f98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1de7a04 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1de7a04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-c8ebb19a-8a85-48f0-a3d2-bbd278f6e9bc\" viewBox=\"0 0 50 30.81\"><path d=\"M0,12.87v-.49c.2-.25.37-.49.73-.49l13.99.05c.82.52.43,1.55-.54,1.52H.83c-.4,0-.6-.32-.83-.59Z\"><\/path><path d=\"M35.27,5.36h9.11c.53,0,1.54.84,1.82,1.3l3.66,8.72c-.23,3.26.38,7.12.02,10.31-.24,2.11-2.54,1.84-4.09,1.81-.62,3.85-6.07,4.56-7.72,1.04-.17-.36-.17-1.05-.61-1.05h-15.58c-1.09,4.39-7.16,4.48-8.16.02-2.16-.28-6.46,1.03-6.81-2.2-.12-1.11-.13-3.97,0-5.07.11-.91,1.25-1,1.54-.17l.03,5.14c.12.49.43.7.92.74,1.37.13,2.94-.09,4.33-.02.99-4.4,7.1-4.4,8.1.01h11.89V2.19c0-.12-.51-.71-.73-.64H9.11c-1.32.26-.05,3.7-1.03,4.15-.5.23-1.07-.03-1.16-.59-.1-.6-.06-2.64.06-3.25.2-.98,1.05-1.74,2.03-1.87h24.16c.92.03,2.09,1.2,2.09,2.1v3.27ZM48.32,19.4l-.02-3.83c-1.23-2.45-2.04-5.41-3.3-7.81-.13-.24-.52-.84-.81-.84h-8.91v19.01h2.53c.81-4.42,7.17-4.4,7.99,0,.53-.08,1.98.16,2.37-.09.26-.17.13-.98.16-1.27h-1.41c-.43,0-1.02-.47-1.17-.88-.22-.6-.24-2.83-.02-3.43.1-.28.64-.85.9-.85h1.71ZM48.32,20.96h-1.17v1.9c.28.29.79.1,1.17.15v-2.05ZM17.32,24.2c-3.18.46-2.61,5.64,1.02,5.02,2.99-.51,2.5-5.53-1.02-5.02ZM41.28,24.2c-.96.15-1.89,1.11-2.01,2.08-.37,3.08,3.54,4.06,4.77,1.65.99-1.96-.62-4.08-2.76-3.73Z\"><\/path><path d=\"M18.68,7.63c.44.48.15,1.27-.5,1.34H4.53c-1.03-.12-1.13-1.44,0-1.57l13.81.03c.1.06.26.11.33.2Z\"><\/path><path d=\"M3.09,16.3l13.32-.02c1.04-.02,1.49,1.22.4,1.56H2.97c-1.05-.12-.87-1.5.13-1.54Z\"><\/path><path d=\"M36.47,8.12c.15-.17.38-.21.6-.23,1.55-.15,4.79-.14,6.34,0,.67.06.67.37.94.91.93,1.91,1.61,4.03,2.52,5.96.27.8-.04,1.15-.83,1.23-2.81.26-6.02-.21-8.87,0-.58-.01-.88-.38-.93-.93-.14-1.48-.16-4.89,0-6.34.02-.18.11-.47.23-.6ZM42.97,9.45h-5.16v4.97h7.21l-2.05-4.97Z\"><\/path><path d=\"M17.78,25.59c1.73,0,1.28,2.78-.39,2.2-1.19-.42-.85-2.2.39-2.2Z\"><\/path><path d=\"M41.76,25.57c1.23-.04,1.6,1.67.52,2.16-1.71.78-2.32-2.11-.52-2.16Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fee5c3f elementor-widget elementor-widget-heading\" data-id=\"fee5c3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Delivery included<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19726ff e-con-full e-flex e-con e-child\" data-id=\"19726ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c8484d elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"8c8484d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-a5b6178d-152f-4a33-bb18-edd466ea6210\" viewBox=\"0 0 49.58 49.6\"><path d=\"M49.52,34.92c-.05-1.63-.1-3.32-.01-4.96-.11-1.28-.77-2.4-1.81-3.07-1.02-.65-2.27-.78-3.45-.36-.08.03-.24.11-.48.25-.11.06-.26.14-.37.2-.29-.78-.87-1.44-1.64-1.85-.92-.5-2.03-.61-3.03-.3-.35.11-.63.29-.9.46-.15.1-.3.19-.45.27-.48-.78-1.29-1.35-2.25-1.59-.96-.23-1.94-.11-2.76.33v-5.15c2.99-1.34,5.2-4.36,5.64-7.74.35-2.71-.46-5.5-2.22-7.63-1.77-2.15-4.36-3.48-7.11-3.66-3.25-.21-6.68-.11-9.98-.02-3.04.08-6.19.17-9.22.02C4.69.36.46,4.4.02,9.13c-.03.35-.02.72,0,1.08.01.31.02.64,0,.93v.03s0,.03,0,.03c.08.29.13.58.19.87.07.37.15.76.26,1.13,1.25,3.95,4.94,6.75,9.18,6.97h14.89s0,8.27,0,8.27c-.39-.57-.76-1.25-1.14-1.95-1.25-2.32-2.66-4.95-5.7-4.2-1.07.26-1.95.92-2.47,1.86-.54.98-.64,2.18-.26,3.33,1.18,2.23,2.34,4.52,3.46,6.74,1.31,2.59,2.67,5.27,4.06,7.87l.11.21c1.68,3.16,2.9,5.44,6.6,6.72.63.22,1.25.34,1.9.47l.44.09h8.93c4.73-.44,8.69-4.54,9.01-9.34.12-1.74.06-3.57.01-5.34ZM32.35,16.83v-5.9c0-.39-.44-1.29-.55-1.49-.63-1.12-1.73-1.82-3.02-1.93-1.29-.11-2.55.42-3.36,1.42-.28.35-.86,1.45-.86,1.91v7.31h-14.69c-5.34-.31-7.73-4.24-7.74-7.98,0-3.62,2.36-7.67,7.54-7.99,1.41-.09,2.86-.12,4.31-.12,1.84,0,3.68.05,5.5.1,3,.08,6.1.16,9.05.02,3.6.27,6.44,2.7,7.25,6.19.77,3.34-.57,6.62-3.44,8.46ZM25.95,33.13c.39-.16.64-.55.66-1.03V11.16c.25-1.24,1.2-1.65,1.9-1.62.8.03,1.66.6,1.8,1.76v16.38c-.03.52.31.95.81,1.02,1.03.15,1.15-.59,1.25-1.13.03-.18.06-.37.12-.53.35-.94,1.25-1.19,1.91-1.12.64.07,1.44.49,1.56,1.41.02.13.02.3.02.48,0,.62,0,1.56.8,1.73,1.01.22,1.2-.63,1.35-1.25.07-.3.14-.62.29-.82.53-.75,1.35-.86,1.95-.7.59.15,1.26.63,1.35,1.51.02.16,0,.41,0,.67-.03.71-.07,1.6.39,2.02.21.19.49.26.83.21.65-.09.78-.68.9-1.2.09-.4.18-.81.47-1.1.51-.51,1.21-.67,1.88-.44.69.24,1.18.85,1.27,1.55-.05,1.21-.01,2.52.03,3.9.18,5.56.37,11.87-6.09,13.43-1.91.46-7.04.4-9.38.23-2.82-.2-5.12-1.72-6.64-4.39-1.48-2.61-2.85-5.38-4.18-8.06-1.32-2.67-2.68-5.43-4.16-8.02-.55-1.13-.09-2.08.62-2.53.29-.18.64-.29,1-.29.52,0,1.06.22,1.5.78l4.57,7.79.04.05c.35.33.79.43,1.18.27Z\"><\/path><path d=\"M22.01,5.9c-.18.04-.34.14-.48.3l-4.25,5.68s-.02-.01-.02-.02c-.11-.08-.25-.24-.39-.4-.24-.28-.49-.56-.76-.64-.43-.14-.84-.03-1.1.28-.28.33-.32.83-.1,1.25.09.18,1.78,1.86,1.96,1.96.18.1.36.14.53.14.31,0,.61-.16.87-.47l4.94-6.62c.18-.41.15-.83-.1-1.13-.25-.3-.66-.42-1.11-.33Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0321a92 elementor-widget elementor-widget-heading\" data-id=\"0321a92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Subscription: 3 months for \u20ac135<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5e48aa e-con-full e-flex e-con e-child\" data-id=\"d5e48aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30a8773 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"30a8773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-232eda75-60ad-4799-ac81-d3806b09542a\" viewBox=\"0 0 43.74 50\"><path d=\"M5.16,50c-.08-.1-.49-.37-.49-.44v-21.34c-.75,0-1.52.66-2.07-.12L0,18.32c.06-.33.25-.59.56-.71l5.47-1.42c-1.18-3.34-1.54-10.25,2.91-11.3,3.12-.74,7.14,2.03,9.72,3.56.36-.22,1.16-.23,1.44-.51s.98-1.92,1.28-2.43c1.13-1.9,3.1-4.84,5.35-5.39,4.41-1.08,7.36,4.82,8.01,8.35l5.25-1.44c1.18-.29,1.21.68,1.46,1.52.84,2.8,1.42,5.68,2.27,8.48-.03.41-.24.71-.64.81l-31.6,8.5h29.26c.22,0,.63.56.54.83-.08,7.48.14,15-.11,22.46l-.38.35H5.16ZM33.09,8.19c-.76-3.03-3.65-8.84-7.42-5.72-1.66,1.37-2.86,3.81-3.91,5.66l1.7.64c3.04-1.18,6.72-3.15,9.63-.59ZM7.4,15.03c1.2-3.6,5.43-3.81,8.63-4.21l1.14-1.4c-3.21-1.99-9.29-5.93-10.24.4-.2,1.35-.09,2.62.11,3.96l.36,1.25ZM31.82,9.26c-1.99-1.79-5.02-.06-7.13.73.33.24.39.93.82.93l6.31-1.67ZM39.93,8.78l-12.4,3.22,2.06,7.81,12.36-3.31-2.02-7.71ZM23.72,11.41c-.27-.68-.99-1.25-1.66-1.51-2.38-.94-4.99.71-4.98,3.27l6.64-1.76ZM15.51,12.39c-2.3.49-5.44.42-6.54,2.93l6.54-1.67v-1.26ZM28.01,20.3l-2.11-7.8-10.19,2.79,2.09,7.73,10.2-2.72ZM14.14,15.61l-12.41,3.32,2.05,7.81,12.37-3.32-2.01-7.82ZM17.95,27.92H6.23v20.51h11.72v-20.51ZM26.45,27.92h-6.94v20.51h6.94v-20.51ZM39.74,27.92h-11.72v20.51h11.72v-20.51Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1a320a elementor-widget elementor-widget-heading\" data-id=\"b1a320a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Gift: 2 U\u2019WA cups<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d08b86b elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d08b86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uwa.sapiens-lab.com\/en\/producto\/montana-sagrada-suscription\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SUBSCRIBE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cdd1077 e-con-full e-flex e-con e-child\" data-id=\"cdd1077\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7be181f elementor-widget elementor-widget-image\" data-id=\"7be181f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"700\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_2.jpg\" class=\"attachment-full size-full wp-image-1464\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_2.jpg 620w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_2-300x339.jpg 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_2-266x300.jpg 266w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-660abe9 e-con-full e-flex e-con e-parent\" data-id=\"660abe9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-95771a0 e-con-full e-flex e-con e-child\" data-id=\"95771a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e708bf elementor-widget elementor-widget-image\" data-id=\"0e708bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"700\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_3.jpg\" class=\"attachment-full size-full wp-image-1471\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_3.jpg 620w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_3-300x339.jpg 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Mockup_Abonnements_3-266x300.jpg 266w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f5f15c e-con-full e-flex e-con e-child\" data-id=\"7f5f15c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8092b5e elementor-widget elementor-widget-heading\" data-id=\"8092b5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Selva Viva Suscription 59\u20ac \/ Month<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80bee8f elementor-widget elementor-widget-heading\" data-id=\"80bee8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Full Experience<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4cb9ee9 e-con-full e-flex e-con e-child\" data-id=\"4cb9ee9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4fd04d elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a4fd04d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-d61e559f-1076-49ef-8fc4-eb97ee1c5c42\" viewBox=\"0 0 33.65 50\"><path d=\"M.52,50c-.77-.07-.57-1.37-.15-1.37h1.81c-.07-.15-.1-.27-.1-.43-.23-9.17.18-18.37,0-27.54l3.88-13.31c.17-2.15-.17-4.48.02-6.62.03-.28.04-.51.32-.66L26.94,0c.39,0,.66.15.72.55.13.81,0,2.14,0,3.02,0,1.31-.13,2.99.13,4.26.86,4.19,2.85,8.59,3.78,12.82-.18,9.17.23,18.37,0,27.54,0,.17-.03.29-.1.43h1.81c.42,0,.62,1.3-.15,1.37H.52ZM11.26,1.37h-4v2.05h4V1.37ZM20.93,1.37h-8.2v10.4c0,1.7,2.46,3.38,4.05,3.38s4.15-1.64,4.15-3.38V1.37ZM26.3,1.37h-3.91v2.05h3.91V1.37ZM11.26,4.79h-3.86l-.15.15v1.86l.15.15h3.86v-2.15ZM26.3,4.79h-3.91v2.15h3.91v-2.15ZM11.26,8.3h-4.05l-3.47,11.62h13.52c.8,0,.69,1.37.1,1.37H3.45v27.1s.15.17.2.19l26.12.06c.36.02.44-.35.44-.64v-27.05s-3.76-12.65-3.76-12.65h-4.05v2.78c0,1.22-.8,2.94-1.67,3.8-3.16,3.12-8.47,1.43-9.32-2.87l-.14-1.03v-2.69Z\"><\/path><path d=\"M16.22,24.35c8.36-.47,14.06,8.63,9.9,15.95-4.08,7.18-14.56,7.23-18.59,0s.81-15.51,8.69-15.95ZM16.41,25.72c-6.92.3-11.14,7.86-7.71,13.9s12.7,6.29,16.24,0c3.59-6.38-1.25-14.22-8.53-13.9Z\"><\/path><path d=\"M18.26,11.56c.43.35.21,1.1-.33,1.22-.31.07-1.89.07-2.2,0-.66-.15-.79-1.17-.1-1.33.35-.08,2.42-.07,2.64.11Z\"><\/path><path d=\"M18.17,28.64c2.14-.24,4.18.51,4.88,2.69,2,6.3-8.91,13.95-12.13,8.13-2.34-4.23,2.98-10.33,7.25-10.81ZM19.66,29.98h-1.51c-.73,0-2.71,1.16-3.32,1.66-2.04,1.69-4.59,5.68-2.01,7.91.13-1.06.49-2.13,1.22-2.93,1.34-1.46,3.42-1.83,4.58-3.52.6-.88,1.02-2.05,1.03-3.12ZM14.09,40.03c1.16.26,2.5-.25,3.51-.82,1.78-1.01,3.5-2.94,4.05-4.93.36-1.3.4-2.58-.59-3.61-.56,2.27-1.39,3.83-3.38,5.12-1.78,1.15-3.49,1.7-3.6,4.25Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b7d392 elementor-widget elementor-widget-heading\" data-id=\"7b7d392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">1kg of specialty coffee<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96d9bc9 e-con-full e-flex e-con e-child\" data-id=\"96d9bc9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bec9dc elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0bec9dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-63625bcd-a9b6-47ce-9234-c0f7dc82e297\" viewBox=\"0 0 50 44.88\"><path d=\"M.03,30.13c-.04-.3-.03-.97,0-1.27.54-4.68,6.88-4.22,6.74.74-.13,4.79-6.18,4.96-6.74.53ZM4.13,32.19c2.26-1.1,2.08-4.78-.35-5.55-1.27,1.67.41,3.02.44,4.63,0,.27-.18.62-.1.93ZM2.47,26.91c-.17-.18-1.03.98-1.12,1.17-.67,1.47-.11,3.7,1.56,4.2.81-1.39-.5-2.45-.62-3.77-.06-.6.06-1.03.18-1.6Z\"><\/path><path d=\"M13.69,25.06c-2.85-1.03-2.56-4.43-.24-5.97,1.27-.84,3.26-1.05,4.54-.14.18.13.56.64.72.62.66-.56,1.74-.76,2.4-1.21,1.18-.81,2.39-2.7,3.57-3.56,1.09-.78,2.24-.37,3.04.57.89-.51,1.53-.78,2.51-.26.34.18.48.49.79.66.71-.72,1.47-1.4,2.16-2.14,3.62-3.88,6.9-8.27,10.54-12.11.48-.51.97-1.05,1.64-1.29,3.37-1.21,6.06,2.62,3.83,5.39-3.99,3.67-8.25,7.04-12.25,10.69-.95.87-1.92,1.74-2.73,2.74,1.44,1.18,1.77,2.66.53,4.15-6.76,6.38-13.02,13.53-19.82,19.83-1.52,1.41-2.88,2.69-4.96,1.15-1.21-.89-1.13-1.7-1.58-2.91-1.4-3.76-1.8-6.76.5-10.35,1.09-1.71,4.33-4.06,4.78-5.58.03-.09.08-.18.04-.29ZM46.28,1.05c-.79.11-1.27.6-1.78,1.14-3.46,3.66-6.57,7.86-10.05,11.53l-.11.29,1.74,1.65,12.45-10.89c1.17-1.73-.18-4.01-2.25-3.72ZM33.56,14.7l-1.8,1.81,1.71,1.71,1.8-1.72-1.7-1.79ZM23.16,17.92l2.44-.25,1.36-1.55c-.24-.31-.68-.74-1.1-.72-.75.04-2.14,1.96-2.7,2.51ZM17.9,38.33l.33-.08,15.98-16.05c.31-.55.38-1.07.02-1.63l-4.66-4.62c-.41-.2-.83,0-1.15.27-3.14,3.42-6.87,6.52-9.96,9.96-3.27,3.64-3.61,8.22-.57,12.15ZM24.33,18.81c-1.36.06-2.84.46-4.07,1.06-.25.12-1.07.51-1.11.75-.03.19.11.58.11.88-.02,2.24-2.37,3.9-4.48,3.87-.39.86-.71,1.76-.86,2.7-.24,1.4,0,2.75-.81,3.98-.27.41-.69.71-.9,1.15-.52,1.11-.17,2.62-.28,3.82,2.05.28,3.29,2.27,3.23,4.26l2.14-2.11c-3.37-4.05-3.32-9.45.15-13.42l6.88-6.93ZM17.6,20.07c-1.95-1.75-5.31.17-4.88,2.74.56-.03,1.24-.08,1.73-.37.62-.37.92-1.07,1.4-1.53.45-.43,1.13-.76,1.75-.84ZM18.18,20.95c-1.69.1-2.03,1.65-3.29,2.42l-1.4.5c2.07,1.16,5.01-.46,4.68-2.93ZM10.85,37.16c.1-1.47-.24-3.2.48-4.55.34-.63.94-1.01,1.19-1.74.3-.87.13-1.8.29-2.69-3.35,2.69-5.38,6.57-4.2,10.94.57-.81,1.2-1.74,2.23-1.96ZM12.72,43.52c.17.04.2-.07.29-.15,1.9-1.45,1.22-4.87-1.17-5.32-.09.57-.34,1-.28,1.6.09.91.74,1.41.99,2.23.17.56.2,1.05.17,1.64ZM11.64,43.71v-1.42c0-.36-1.07-1.62-1.07-2.15v-1.47s.27-.26-.05-.24c-1.85,1.4-1.3,5,1.12,5.27Z\"><\/path><path d=\"M4.5,15.8c4.94-.22,5.57,6.14.84,6.7-5.52.65-6.08-6.47-.84-6.7ZM5.74,18.41c.39-.06,1.03,0,1.46,0,.02,0,.12.15.24.1-.97-2.33-4.87-2.24-5.55.24.47.42,1.27.52,1.89.45.68-.08,1.35-.69,1.95-.78ZM7.54,19.59c-1.93-.8-3.26,1.41-5.24.5-.12-.06-.18.03-.13.13.08.18.61.66.79.78,1.5.98,4.05.46,4.58-1.41Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-751dcdd elementor-widget elementor-widget-heading\" data-id=\"751dcdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Freshly roasted coffee<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7596841 e-con-full e-flex e-con e-child\" data-id=\"7596841\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9d7f7f elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f9d7f7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-c8ebb19a-8a85-48f0-a3d2-bbd278f6e9bc\" viewBox=\"0 0 50 30.81\"><path d=\"M0,12.87v-.49c.2-.25.37-.49.73-.49l13.99.05c.82.52.43,1.55-.54,1.52H.83c-.4,0-.6-.32-.83-.59Z\"><\/path><path d=\"M35.27,5.36h9.11c.53,0,1.54.84,1.82,1.3l3.66,8.72c-.23,3.26.38,7.12.02,10.31-.24,2.11-2.54,1.84-4.09,1.81-.62,3.85-6.07,4.56-7.72,1.04-.17-.36-.17-1.05-.61-1.05h-15.58c-1.09,4.39-7.16,4.48-8.16.02-2.16-.28-6.46,1.03-6.81-2.2-.12-1.11-.13-3.97,0-5.07.11-.91,1.25-1,1.54-.17l.03,5.14c.12.49.43.7.92.74,1.37.13,2.94-.09,4.33-.02.99-4.4,7.1-4.4,8.1.01h11.89V2.19c0-.12-.51-.71-.73-.64H9.11c-1.32.26-.05,3.7-1.03,4.15-.5.23-1.07-.03-1.16-.59-.1-.6-.06-2.64.06-3.25.2-.98,1.05-1.74,2.03-1.87h24.16c.92.03,2.09,1.2,2.09,2.1v3.27ZM48.32,19.4l-.02-3.83c-1.23-2.45-2.04-5.41-3.3-7.81-.13-.24-.52-.84-.81-.84h-8.91v19.01h2.53c.81-4.42,7.17-4.4,7.99,0,.53-.08,1.98.16,2.37-.09.26-.17.13-.98.16-1.27h-1.41c-.43,0-1.02-.47-1.17-.88-.22-.6-.24-2.83-.02-3.43.1-.28.64-.85.9-.85h1.71ZM48.32,20.96h-1.17v1.9c.28.29.79.1,1.17.15v-2.05ZM17.32,24.2c-3.18.46-2.61,5.64,1.02,5.02,2.99-.51,2.5-5.53-1.02-5.02ZM41.28,24.2c-.96.15-1.89,1.11-2.01,2.08-.37,3.08,3.54,4.06,4.77,1.65.99-1.96-.62-4.08-2.76-3.73Z\"><\/path><path d=\"M18.68,7.63c.44.48.15,1.27-.5,1.34H4.53c-1.03-.12-1.13-1.44,0-1.57l13.81.03c.1.06.26.11.33.2Z\"><\/path><path d=\"M3.09,16.3l13.32-.02c1.04-.02,1.49,1.22.4,1.56H2.97c-1.05-.12-.87-1.5.13-1.54Z\"><\/path><path d=\"M36.47,8.12c.15-.17.38-.21.6-.23,1.55-.15,4.79-.14,6.34,0,.67.06.67.37.94.91.93,1.91,1.61,4.03,2.52,5.96.27.8-.04,1.15-.83,1.23-2.81.26-6.02-.21-8.87,0-.58-.01-.88-.38-.93-.93-.14-1.48-.16-4.89,0-6.34.02-.18.11-.47.23-.6ZM42.97,9.45h-5.16v4.97h7.21l-2.05-4.97Z\"><\/path><path d=\"M17.78,25.59c1.73,0,1.28,2.78-.39,2.2-1.19-.42-.85-2.2.39-2.2Z\"><\/path><path d=\"M41.76,25.57c1.23-.04,1.6,1.67.52,2.16-1.71.78-2.32-2.11-.52-2.16Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc9f20a elementor-widget elementor-widget-heading\" data-id=\"dc9f20a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Delivery included<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5c9d7af e-con-full e-flex e-con e-child\" data-id=\"5c9d7af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bee44e7 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bee44e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-a5b6178d-152f-4a33-bb18-edd466ea6210\" viewBox=\"0 0 49.58 49.6\"><path d=\"M49.52,34.92c-.05-1.63-.1-3.32-.01-4.96-.11-1.28-.77-2.4-1.81-3.07-1.02-.65-2.27-.78-3.45-.36-.08.03-.24.11-.48.25-.11.06-.26.14-.37.2-.29-.78-.87-1.44-1.64-1.85-.92-.5-2.03-.61-3.03-.3-.35.11-.63.29-.9.46-.15.1-.3.19-.45.27-.48-.78-1.29-1.35-2.25-1.59-.96-.23-1.94-.11-2.76.33v-5.15c2.99-1.34,5.2-4.36,5.64-7.74.35-2.71-.46-5.5-2.22-7.63-1.77-2.15-4.36-3.48-7.11-3.66-3.25-.21-6.68-.11-9.98-.02-3.04.08-6.19.17-9.22.02C4.69.36.46,4.4.02,9.13c-.03.35-.02.72,0,1.08.01.31.02.64,0,.93v.03s0,.03,0,.03c.08.29.13.58.19.87.07.37.15.76.26,1.13,1.25,3.95,4.94,6.75,9.18,6.97h14.89s0,8.27,0,8.27c-.39-.57-.76-1.25-1.14-1.95-1.25-2.32-2.66-4.95-5.7-4.2-1.07.26-1.95.92-2.47,1.86-.54.98-.64,2.18-.26,3.33,1.18,2.23,2.34,4.52,3.46,6.74,1.31,2.59,2.67,5.27,4.06,7.87l.11.21c1.68,3.16,2.9,5.44,6.6,6.72.63.22,1.25.34,1.9.47l.44.09h8.93c4.73-.44,8.69-4.54,9.01-9.34.12-1.74.06-3.57.01-5.34ZM32.35,16.83v-5.9c0-.39-.44-1.29-.55-1.49-.63-1.12-1.73-1.82-3.02-1.93-1.29-.11-2.55.42-3.36,1.42-.28.35-.86,1.45-.86,1.91v7.31h-14.69c-5.34-.31-7.73-4.24-7.74-7.98,0-3.62,2.36-7.67,7.54-7.99,1.41-.09,2.86-.12,4.31-.12,1.84,0,3.68.05,5.5.1,3,.08,6.1.16,9.05.02,3.6.27,6.44,2.7,7.25,6.19.77,3.34-.57,6.62-3.44,8.46ZM25.95,33.13c.39-.16.64-.55.66-1.03V11.16c.25-1.24,1.2-1.65,1.9-1.62.8.03,1.66.6,1.8,1.76v16.38c-.03.52.31.95.81,1.02,1.03.15,1.15-.59,1.25-1.13.03-.18.06-.37.12-.53.35-.94,1.25-1.19,1.91-1.12.64.07,1.44.49,1.56,1.41.02.13.02.3.02.48,0,.62,0,1.56.8,1.73,1.01.22,1.2-.63,1.35-1.25.07-.3.14-.62.29-.82.53-.75,1.35-.86,1.95-.7.59.15,1.26.63,1.35,1.51.02.16,0,.41,0,.67-.03.71-.07,1.6.39,2.02.21.19.49.26.83.21.65-.09.78-.68.9-1.2.09-.4.18-.81.47-1.1.51-.51,1.21-.67,1.88-.44.69.24,1.18.85,1.27,1.55-.05,1.21-.01,2.52.03,3.9.18,5.56.37,11.87-6.09,13.43-1.91.46-7.04.4-9.38.23-2.82-.2-5.12-1.72-6.64-4.39-1.48-2.61-2.85-5.38-4.18-8.06-1.32-2.67-2.68-5.43-4.16-8.02-.55-1.13-.09-2.08.62-2.53.29-.18.64-.29,1-.29.52,0,1.06.22,1.5.78l4.57,7.79.04.05c.35.33.79.43,1.18.27Z\"><\/path><path d=\"M22.01,5.9c-.18.04-.34.14-.48.3l-4.25,5.68s-.02-.01-.02-.02c-.11-.08-.25-.24-.39-.4-.24-.28-.49-.56-.76-.64-.43-.14-.84-.03-1.1.28-.28.33-.32.83-.1,1.25.09.18,1.78,1.86,1.96,1.96.18.1.36.14.53.14.31,0,.61-.16.87-.47l4.94-6.62c.18-.41.15-.83-.1-1.13-.25-.3-.66-.42-1.11-.33Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e197800 elementor-widget elementor-widget-heading\" data-id=\"e197800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Subscription: 3 months for \u20ac177<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61ecff8 e-con-full e-flex e-con e-child\" data-id=\"61ecff8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78a53e5 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"78a53e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-232eda75-60ad-4799-ac81-d3806b09542a\" viewBox=\"0 0 43.74 50\"><path d=\"M5.16,50c-.08-.1-.49-.37-.49-.44v-21.34c-.75,0-1.52.66-2.07-.12L0,18.32c.06-.33.25-.59.56-.71l5.47-1.42c-1.18-3.34-1.54-10.25,2.91-11.3,3.12-.74,7.14,2.03,9.72,3.56.36-.22,1.16-.23,1.44-.51s.98-1.92,1.28-2.43c1.13-1.9,3.1-4.84,5.35-5.39,4.41-1.08,7.36,4.82,8.01,8.35l5.25-1.44c1.18-.29,1.21.68,1.46,1.52.84,2.8,1.42,5.68,2.27,8.48-.03.41-.24.71-.64.81l-31.6,8.5h29.26c.22,0,.63.56.54.83-.08,7.48.14,15-.11,22.46l-.38.35H5.16ZM33.09,8.19c-.76-3.03-3.65-8.84-7.42-5.72-1.66,1.37-2.86,3.81-3.91,5.66l1.7.64c3.04-1.18,6.72-3.15,9.63-.59ZM7.4,15.03c1.2-3.6,5.43-3.81,8.63-4.21l1.14-1.4c-3.21-1.99-9.29-5.93-10.24.4-.2,1.35-.09,2.62.11,3.96l.36,1.25ZM31.82,9.26c-1.99-1.79-5.02-.06-7.13.73.33.24.39.93.82.93l6.31-1.67ZM39.93,8.78l-12.4,3.22,2.06,7.81,12.36-3.31-2.02-7.71ZM23.72,11.41c-.27-.68-.99-1.25-1.66-1.51-2.38-.94-4.99.71-4.98,3.27l6.64-1.76ZM15.51,12.39c-2.3.49-5.44.42-6.54,2.93l6.54-1.67v-1.26ZM28.01,20.3l-2.11-7.8-10.19,2.79,2.09,7.73,10.2-2.72ZM14.14,15.61l-12.41,3.32,2.05,7.81,12.37-3.32-2.01-7.82ZM17.95,27.92H6.23v20.51h11.72v-20.51ZM26.45,27.92h-6.94v20.51h6.94v-20.51ZM39.74,27.92h-11.72v20.51h11.72v-20.51Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50ce089 elementor-widget elementor-widget-heading\" data-id=\"50ce089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Gifts: 1 Bodum French press + 2 U\u2019WA cups<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03e3feb elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"03e3feb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/uwa.sapiens-lab.com\/en\/producto\/selva-viva\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SUBSCRIBE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CAFFEINE Curated for you Travel to Colombia, One Cup at a Time! &#8220;Immerse yourself each month in the vibrant world of Colombian specialty coffee with our renewable 3-month subscriptions, designed for lovers of flavor, discovery, and authenticity. Each plan includes a selection of exceptional coffees, shipping included, and, depending on the chosen option, exclusive gifts. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1801","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subscriptions - UWA Caf\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uwa.sapiens-lab.com\/suscripcion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subscriptions - UWA Caf\u00e9\" \/>\n<meta property=\"og:description\" content=\"CAFFEINE Curated for you Travel to Colombia, One Cup at a Time! &#8220;Immerse yourself each month in the vibrant world of Colombian specialty coffee with our renewable 3-month subscriptions, designed for lovers of flavor, discovery, and authenticity. Each plan includes a selection of exceptional coffees, shipping included, and, depending on the chosen option, exclusive gifts. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uwa.sapiens-lab.com\/suscripcion\/\" \/>\n<meta property=\"og:site_name\" content=\"UWA Caf\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61569251725677\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T20:42:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1709\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/\",\"name\":\"Subscriptions - UWA Caf\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Ilustracion_ramo-de-tazas-copie-scaled.png\",\"datePublished\":\"2025-07-17T20:53:28+00:00\",\"dateModified\":\"2026-02-04T20:42:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Ilustracion_ramo-de-tazas-copie-scaled.png\",\"contentUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Ilustracion_ramo-de-tazas-copie-scaled.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/suscripcion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subscriptions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"name\":\"U'WA Caf\u00e9\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\",\"name\":\"U'WA Caf\u00e9\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"contentUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"width\":510,\"height\":340,\"caption\":\"U'WA Caf\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61569251725677\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subscriptions - UWA Caf\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/","og_locale":"en_US","og_type":"article","og_title":"Subscriptions - UWA Caf\u00e9","og_description":"CAFFEINE Curated for you Travel to Colombia, One Cup at a Time! &#8220;Immerse yourself each month in the vibrant world of Colombian specialty coffee with our renewable 3-month subscriptions, designed for lovers of flavor, discovery, and authenticity. Each plan includes a selection of exceptional coffees, shipping included, and, depending on the chosen option, exclusive gifts. [&hellip;]","og_url":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/","og_site_name":"UWA Caf\u00e9","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61569251725677","article_modified_time":"2026-02-04T20:42:23+00:00","og_image":[{"width":1709,"height":2560,"url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/","url":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/","name":"Subscriptions - UWA Caf\u00e9","isPartOf":{"@id":"https:\/\/uwa.sapiens-lab.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/#primaryimage"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/#primaryimage"},"thumbnailUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled.png","datePublished":"2025-07-17T20:53:28+00:00","dateModified":"2026-02-04T20:42:23+00:00","breadcrumb":{"@id":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uwa.sapiens-lab.com\/suscripcion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/#primaryimage","url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled.png","contentUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Ilustracion_ramo-de-tazas-copie-scaled.png"},{"@type":"BreadcrumbList","@id":"https:\/\/uwa.sapiens-lab.com\/suscripcion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/uwa.sapiens-lab.com\/"},{"@type":"ListItem","position":2,"name":"Subscriptions"}]},{"@type":"WebSite","@id":"https:\/\/uwa.sapiens-lab.com\/#website","url":"https:\/\/uwa.sapiens-lab.com\/","name":"U'WA Caf\u00e9","description":"","publisher":{"@id":"https:\/\/uwa.sapiens-lab.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uwa.sapiens-lab.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/uwa.sapiens-lab.com\/#organization","name":"U'WA Caf\u00e9","url":"https:\/\/uwa.sapiens-lab.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/","url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","contentUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","width":510,"height":340,"caption":"U'WA Caf\u00e9"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61569251725677"]}]}},"_links":{"self":[{"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/pages\/1801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/comments?post=1801"}],"version-history":[{"count":3,"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/pages\/1801\/revisions"}],"predecessor-version":[{"id":3282,"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/pages\/1801\/revisions\/3282"}],"wp:attachment":[{"href":"https:\/\/uwa.sapiens-lab.com\/en\/wp-json\/wp\/v2\/media?parent=1801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}