{"id":349,"date":"2025-07-09T12:09:06","date_gmt":"2025-07-09T17:09:06","guid":{"rendered":"https:\/\/uwa.nfvgdigital.com\/?page_id=349"},"modified":"2025-08-05T08:20:21","modified_gmt":"2025-08-05T13:20:21","slug":"qui-sommes-nous","status":"publish","type":"page","link":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/","title":{"rendered":"Qui Sommes &#8211; Nous"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"349\" class=\"elementor elementor-349\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a500f9 e-con-full e-flex e-con e-parent\" data-id=\"3a500f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6ca9d60 e-con-full e-flex e-con e-child\" data-id=\"6ca9d60\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2a4c2 elementor-widget elementor-widget-heading\" data-id=\"3c2a4c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">QUAND LE CAF\u00c9 A<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-169c430 elementor-widget elementor-widget-heading\" data-id=\"169c430\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le go\u00fbt de la paix<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d87588e elementor-widget elementor-widget-text-editor\" data-id=\"d87588e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>U\u2019WA est bien plus qu\u2019un caf\u00e9 : c\u2019est un projet de lien, de sens et de transformation !<\/p><p>N\u00e9 de l\u2019union entre la Colombie et la France, notre engagement repose sur une conviction forte : le caf\u00e9 peut \u00eatre un vecteur de changement social, un pont entre les peuples, et un t\u00e9moin vivant de r\u00e9conciliation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb79d15 e-con-full e-flex e-con e-parent\" data-id=\"fb79d15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4afa438 e-con-full e-flex e-con e-child\" data-id=\"4afa438\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0952ca elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"e0952ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"750\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2.png\" class=\"attachment-full size-full wp-image-2496\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2.png 1080w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2-300x208.png 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2-1024x711.png 1024w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2-768x533.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d18c3 elementor-widget elementor-widget-heading\" data-id=\"b3d18c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un mod\u00e8le<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf6b2fd elementor-widget elementor-widget-heading\" data-id=\"bf6b2fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DURABLE ET \u00c9QUITABLE<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d1860f e-con-full e-flex e-con e-child\" data-id=\"1d1860f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-06500c9 e-con-full e-flex e-con e-child\" data-id=\"06500c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52ab75d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"52ab75d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-131edd7d-b404-4e3f-af76-f3acf0f71820\" viewBox=\"0 0 120 91.12\"><path d=\"M22.68,25.12c-8.67-.58-14.04-9.1-10.89-17.24C14.22,1.57,21.96-1.83,28.24,1.01c1.28.58,2,.86,1.54,2.47s-2.78.14-3.67-.1c-6.15-1.65-12.26,2.71-12.25,9.16,0,9.76,12.8,13.25,17.73,4.93,1.4-2.37.94-3.29,1.31-5.66.29-1.87,2.69-1.68,2.97-.26,1.09,5.67-4.43,12.82-10.2,13.31v25.88h32.85v-12.94c-7.97-.86-13.22-7.96-11.27-15.87,1.74-7.04,9.41-10.96,16.24-8.63,1.12.38,2.73.91,2.46,2.42-.42,2.32-3.78.14-5.34-.03-8.23-.89-13.61,7.73-9.26,14.73s15.46,5.06,17.3-3.02c.4-1.75-.25-5.02,2.39-4.24,1.67.5.62,4.64.24,5.87-1.3,4.26-5.34,7.82-9.78,8.52v13.19h31.61v-25.63c-9.6-.71-14.88-11.23-9.61-19.44,2.83-4.41,8.25-6.49,13.36-5.33,1.37.31,4.17,1.04,3.62,2.88-.63,2.1-3.91,0-5.56-.19-8.46-.9-13.78,9.24-8.27,15.74,4.85,5.72,14.21,3.9,16.42-3.25.32-1.05.45-4.07.74-4.48.98-1.38,2.6-.27,2.76,1.26.34,3.28-1.94,7.72-4.37,9.83-1.86,1.61-3.88,2.2-6.09,3.12v25.51h12.07c.19,0,.96.64,1.08.91l10.75,19.62-11.12,19.51-1.21.29c-35.45.17-70.85-.32-106.29-.25-1.14-.11-1.7-1.17-1.16-2.19l9.75-17.36L.14,53c-.46-.68.32-2.25,1.01-2.25h21.53v-25.63ZM36.36,87.84l9.47-16.78-10.09-17.31H4.01c2.39,4.9,5.43,9.55,7.84,14.43,1.12,2.25,1.85,2.45.66,4.9-2.42,4.97-5.95,9.7-8.25,14.77h32.1ZM39.85,88.08h31.48l9.28-17.01-9.28-17.34h-31.98l9.72,17.3-.29,1.21c-2.26,4.84-6.73,10.13-8.74,14.9-.13.31-.26.56-.2.92ZM107.04,53.74h-32.1l8.96,17.32-8.6,16.27-.11.76h32.1l9.46-16.8-9.7-17.55Z\"><\/path><path d=\"M71.64,13.96c1.43-.26,2.35,1.33,1.42,2.44l-12.56,12.57c-.58.27-1.09.21-1.63-.11-.32-.19-5.05-4.91-5.21-5.24-.57-1.24.39-2.43,1.68-2.2,1.15.21,3.86,4.04,4.5,3.93,2.09-1.38,10.2-11.1,11.79-11.39Z\"><\/path><path d=\"M37.05,1.78c.37.37.47,1.62.07,2.07l-12.95,12.7c-.19.09-.37.09-.57.06-.57-.09-5.86-5.3-6.05-5.93-.4-1.3.92-2.04,2.16-1.64.94.3,3.8,3.87,4.09,3.87L34.98,1.71c.45-.4,1.7-.3,2.07.07Z\"><\/path><path d=\"M88.44,9.25c1.81-1.8,4.51,3.11,6,3.66l10.87-11.05c1.72-1.22,3.64.51,2.11,2.11-4.08,3.21-7.62,8.75-11.57,11.82-.47.37-1.21.92-1.82.83-.5-.08-4.95-4.4-5.41-5.06s-.82-1.68-.19-2.31Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b494ec7 elementor-widget elementor-widget-heading\" data-id=\"b494ec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Notre mod\u00e8le repose sur une cha\u00eene transparente.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8fe843 e-con-full e-flex e-con e-child\" data-id=\"a8fe843\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2e134f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b2e134f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-2667ee58-e268-42aa-a32b-69760670fc76\" viewBox=\"0 0 96.24 120\"><path d=\"M82.34,73.23h12.06v-3.01h-37.15l.06-.56c.17-1.48.04-2.37-.41-2.82-.45-.44-1.34-.57-2.82-.41l-.56.06v-5.18l.18-.15c.5-.41,1.13-.52,1.75-.63.27-.05.54-.09.79-.17,19.12-5.81,24.66-22.31,21.67-36.08C75.01,10.95,63.12-2.24,43.85.32c-17.25,2.3-24.83,15.95-26.07,26.94-1.25,11.02,3.14,26.08,19.6,32.24.79.29,1.63.54,2.44.77.86.25,1.75.51,2.59.83l.32.12v5.28l-.56-.06c-1.48-.17-2.37-.04-2.82.41s-.57,1.34-.41,2.82l.06.56H1.85v3.01h12.06L.21,92.28c-1.24,6.53,3.34,12.99,8.32,15.78,5.45,3.05,11.88,2.94,17.2-.28,5.26-3.19,8.31-8.73,8.18-14.85l-13.93-19.7h18.96v45.98c.04.06.34.35.86.79h16.64c.52-.44.82-.74.87-.87v-45.9s18.95,0,18.95,0l-13.93,19.7c-.14,6.1,2.91,11.64,8.16,14.83,5.33,3.24,11.77,3.35,17.22.3,4.98-2.78,9.56-9.25,8.32-15.78l-13.7-19.05ZM30.9,95.31c-1.41,8.26-8.06,11.95-14.03,11.95-.02,0-.04,0-.07,0-5.92-.03-12.5-3.73-13.83-11.95l-.09-.59h28.12l-.1.59ZM29.5,91.72H4.12l12.94-17.43,12.43,17.43ZM33.9,54.61c-9.6-5.73-14.75-16.12-13.45-27.12,1.48-12.49,12.14-23.19,24.26-24.35,13.35-1.28,24.92,5.84,29.48,18.17,4.48,12.11.51,24.77-10.12,32.25-4.8,3.37-10.3,5.07-15.84,5.07-4.91,0-9.84-1.33-14.33-4.01ZM50.52,61.42v5.03h-4.79v-5.03h4.79ZM54.53,116.99h-12.82v-39.99h12.82v39.99ZM54.53,74.24h-12.82v-5.03h12.82v5.03ZM79.18,74.29l12.94,17.43h-25.37l12.43-17.43ZM93.27,95.31c-1.33,8.22-7.89,11.92-13.82,11.95-.02,0-.04,0-.07,0-5.99,0-12.63-3.69-14.04-11.94l-.1-.59h28.12l-.09.59Z\"><\/path><path d=\"M64.64,22.45l-16.09,12.08c-.6.3-1.01.13-1.31,0-1.28-.53-2.67-1.51-4.03-2.46-1.39-.98-2.82-1.99-3.95-2.39-.45-.16-.85-.22-1.3-.17l-7.88,7.86,1.93,1.81,6.57-6.47,9.42,5.48.51-.06,17.68-13.46-1.57-2.21Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe2efbc elementor-widget elementor-widget-heading\" data-id=\"fe2efbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Un commerce \u00e9quitable.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7a2f77 e-con-full e-flex e-con e-child\" data-id=\"d7a2f77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f6fd83 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5f6fd83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-876c08f2-fc68-42a1-802b-23ebf7951289\" viewBox=\"0 0 114.48 120\"><path d=\"M57.66,39.84c-.18-1.97-2.84-11.58-4.39-12.38l-.36-.08c-12.03,7-21.24-3.48-23.45-14.81-.74-3.79-2.1-11.83,3.35-12.42,14.27-1.53,32.32,8.92,22.99,24.81l2.97,6.5,2.96-6.22c-5.06-9.7,2.92-16.72,12.08-18.15,5.81-.9,9.2-.71,8.85,6.1-.51,9.9-7.9,20.31-18.67,14.42-2.37,5.4-3.17,11.14-3.02,17.03h30.63c.32,0,2.17,1.06,2.47,1.37,2.21,2.25,1.31,6.47,1.54,9.31,1.93.06,4.64,3.05,4.64,4.84v28.15c4.77-.84,12.1-.21,13.87,5.22,2.02,6.2-4.54,8.25-9.06,9.89-10.86,3.94-26.97,7.64-38.46,8.78s-27.18-4.15-37.4,1.33c-3.74,2.01-8.27,7.33-12.55,6.34C12.22,118.85.67,106.62.04,102.12c-.43-3.1,3.04-6.49,5.16-8.45,4.56-4.22,10.33-7.9,15.62-11.16.49-6.82-.5-14.23.03-20.98.25-3.17,1.75-5.43,4.83-6.43.5-2.35-.38-5.29.46-7.51.38-1,2.35-2.94,3.38-2.94h28.15c-.1-1.56.14-3.27,0-4.81ZM39.12,3.44c-2-.2-4.28.15-6.32,0-1.19,0-.51,6.01-.38,6.97,1.29,9.38,8.38,20.35,18.92,14.04l-1.85-2.61c-1.62-.45-7.58,2.11-6.95-1.49.27-1.54,2.63-1.38,3.85-1.53-.88-1.54-4.97-2.66-3.59-4.82,1.1-1.72,3.28.05,4.27.97.63,0-.04-3.16,2.2-3.17,2.66,0,.97,4.47,1,5.99l3.4,4.04c5.5-9.89-5.76-17.51-14.56-18.4ZM67.6,22.72l-1.43,2.01c5.73,3.84,10.62-1.38,12.23-6.72.37-1.22,1.58-7.24.7-7.85-6.87-.51-17.44,2.92-15.4,11.69.34.36,3.27-2.91,3.71-3.29.51-.42,2.07-1.65,2.59-1.81,2.32-.71,2.99,1.79,1.39,3.05v.39c1.26.23,1.39,1.8.56,2.64-1.2,1.2-3.62-.54-4.36-.1ZM92.27,55.08v-5.63c0-.86-1.17-1.7-2.05-1.52l-60.3.16c-.17.15-.83.74-.83.82v6.18h63.17ZM24.15,60.99v19.09c1.57-.33,3.04-1.46,4.57-2.16,18.53-8.43,35.65-5.84,54.08,1.33,5.29,2.06,9.32,4.48,7.55,10.99l6.61-1.54v-27.72c-.14-1.07-.85-2.22-1.93-2.47l-69.16.07c-.86.49-1.57,1.41-1.72,2.4ZM52.38,75.76c-13.99.11-25.74,6.13-36.83,13.99-2.54,1.8-11.77,8.64-12.23,11.42-.33,2.01,4.75,7.7,6.26,9.28s6.42,6.33,8.43,6.36c1.34.02,7.79-5.23,9.79-6.28,9.71-5.08,21.3-1.83,31.64-1.33,7.52.36,17.17-1.8,24.58-3.43,5.79-1.27,21.48-4.77,25.8-7.99,1.75-1.3,1.72-3.34.16-4.8-4.64-4.34-19.04,1.13-25,1.65-7.42.65-15-2.93-22.05-1.18-1.14.28-3.51,1.95-4.12-.11-.73-2.45,4.09-3.44,5.88-3.62,6.42-.64,14.38,2.69,19.95,1.55,3.05-.62,3.68-4.92,1.44-6.81s-10.53-4.19-13.6-5.08c-6.37-1.84-13.45-3.68-20.11-3.63Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c582be elementor-widget elementor-widget-heading\" data-id=\"7c582be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">\u00c9coresponsables, nous favorisons des pratiques agricoles durables.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61c18d8 e-con-full e-flex e-con e-child\" data-id=\"61c18d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db4204c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"db4204c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-9ebc853e-2372-4585-94f9-f0d552c674b4\" viewBox=\"0 0 120.07 120\"><path d=\"M87.67,77.68c.78,4.36-3.25,8.43-7.72,7.72.54,4.62-3.13,8.22-7.72,7.97.53,5.47-4.74,9.06-9.72,6.61-1.02-.5-1.63-1.32-2.57-1.86-4.7,5.94-13.37,2.82-13.11-4.75-4.48.5-8.16-3.3-7.72-7.72-4.53.35-8.1-3.22-7.83-7.73-.85-.23-1.74-.11-2.64-.35-4.49-1.18-6.56-6.42-4.18-10.43.33-.56,2.2-2.37,2.17-2.74-12.46-16.56-.4-39.43,20.57-37.76,4.48.36,8.89,2.56,12.46,5.16,10.77-9.28,27.35-6.81,35.09,5.06,5.52,8.48,4.83,20.38-1.83,28.03-.06.35,1.13,1.32,1.43,1.75,3.56,5.06-.65,11.74-6.68,11.04ZM72.68,29.19c-4.73.49-8.67,2.69-12.15,5.77-3.13,2.77-9.67,8.94-12.05,12.1-3.04,4.03.48,8.4,4.92,6.42l13.66-13.25.7-.05,23,22.54c11.69-14.2.34-35.42-18.08-33.53ZM60.28,79.92c3.16-.33,6.41,1.52,7.52,4.56.36.99.29,2.23.58,2.91.07.15,1.74,1.82,1.99,1.99,4.17,3.01,8.77-1.85,5.6-5.84l-12.66-12.74c-.9-1.71.71-3.04,2.46-1.72,4.37,3.29,8.42,9.31,12.86,12.79,4.72,2.13,8.19-2.43,4.82-6.56-3.47-4.26-8.71-8.07-12.32-12.33-1.16-1.79,1.08-3.01,2.48-1.73,4.24,3.4,8.34,9.46,12.57,12.58,3.58,2.65,7.92-1.1,6.03-5.04l-24.83-24.97-12.44,12.2c-7.94,3.61-14.07-4.58-8.23-11.46,3.12-3.67,7.36-6.93,10.58-10.58-9.32-7.7-24.07-4.9-30,5.6-4.04,7.16-3.43,15.72,1.31,22.35.12.17-.05.42.43.31,2.32-2.1,4.61-5.43,7.98-5.72,4.59-.39,8.05,3.21,7.84,7.72,4.58-.14,8.26,3.28,7.72,7.97,4.5-.57,8.44,3.2,7.72,7.72ZM36.81,59.56c-.63.13-1.66.89-2.18,1.31-1.33,1.08-7.05,6.76-7.67,8.02-1.94,3.92,2.34,7.54,5.91,5.17.94-.63,7.75-7.49,8.29-8.4,1.88-3.2-.76-6.85-4.35-6.09ZM45.29,67.27c-.73.06-1.71.51-2.31.95-1.03.74-7.45,7.17-8.05,8.13-2.29,3.69,1.89,8.18,5.92,5.42,1-.69,7.75-7.51,8.24-8.44,1.51-2.86-.56-6.31-3.79-6.06ZM52.25,75.24c-.51.1-1.02.49-1.43.81-1.1.85-7.62,7.31-8.17,8.26-2.25,3.83,2.21,8.1,6.42,4.92,1.26-.95,7.37-7.08,7.93-8.25,1.58-3.32-1.11-6.48-4.74-5.74ZM60.47,82.97c-.55.09-1.1.37-1.56.68-.8.56-8.2,7.98-8.56,8.63-1.99,3.59,2.18,7.71,5.93,5.18.86-.58,7.99-7.71,8.45-8.49,1.74-2.97-.9-6.55-4.26-6ZM67.01,90.63l-4.72,5.14c2.42,4,8.3,1.62,6.76-3.08-.15-.47-1.61-2.38-2.05-2.06Z\"><\/path><path d=\"M16.46,101.33c-.31,1.73.12,5.26-.36,6.74-.36,1.11-1.99,1.3-2.65.38-.84-1.18.46-9.26.27-11.22l1.12-1.12,10.65.55c.99.26,1.43,1.19.99,2.13-.86,1.84-5.86.01-7.54.68,18.46,19.48,48.36,23.13,71.19,8.94,21.81-13.56,31.11-38.59,24.9-63.45-.44-1.75-3.1-6.92.38-6.37,1.2.19,2.18,4.31,2.5,5.48,8.17,29.7-7.65,60.89-36.17,71.9-22.78,8.79-48.55,2.93-65.3-14.63Z\"><\/path><path d=\"M103.61,18.66c.31-1.73-.12-5.26.36-6.74s2.81-1.15,2.89.38c-.14,2.55-.09,5.19-.26,7.73-.04.59-.27,2.97-.48,3.26-.15.22-.51.37-.75.49l-10.79-.44c-.99-.26-1.43-1.19-.99-2.13.86-1.84,5.86-.01,7.54-.68C84.65,2.99,58.11-1.9,36.21,8.16,9.14,20.6-3.75,51.93,6.51,80.03l-.24.96c-2.76,1.95-3.6-3.13-4.13-5.06C-4.81,50.67,5.56,23.67,27.43,9.6c24.35-15.67,56.29-11.79,76.17,9.07Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f1efb2 elementor-widget elementor-widget-heading\" data-id=\"2f1efb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Nous travaillons en lien direct avec les producteurs.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf1870c e-con-full e-flex e-con e-parent\" data-id=\"bf1870c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-527bf94 e-con-full e-flex e-con e-child\" data-id=\"527bf94\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17c12a0 elementor-widget elementor-widget-heading\" data-id=\"17c12a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un caf\u00e9 de sp\u00e9cialit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d32df1a elementor-widget elementor-widget-heading\" data-id=\"d32df1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ENGAG\u00c9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24e0e20 elementor-widget elementor-widget-text-editor\" data-id=\"24e0e20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous s\u00e9lectionnons exclusivement des caf\u00e9s de sp\u00e9cialit\u00e9, cultiv\u00e9s dans plusieurs r\u00e9gions embl\u00e9matiques de Colombie. Des montagnes luxuriantes aux vall\u00e9es plus arides, chaque terroir apporte sa propre richesse aromatique, son identit\u00e9, et son histoire.<\/p><p>Ces caf\u00e9s sont issus de pratiques agricoles respectueuses de l\u2019environnement, d\u2019une cueillette manuelle rigoureuse, et d\u2019un savoir-faire transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration.<\/p><p>Mais ce qui rend notre caf\u00e9 vraiment unique, c\u2019est la force humaine et symbolique de ceux qui le produisent.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e81da9c e-con-full e-flex e-con e-child\" data-id=\"e81da9c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f52326 e-con-full e-flex e-con e-parent\" data-id=\"9f52326\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a5fd904 e-con-full e-flex e-con e-child\" data-id=\"a5fd904\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f49dbc0 e-con-full e-flex e-con e-child\" data-id=\"f49dbc0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5abac26 elementor-widget elementor-widget-heading\" data-id=\"5abac26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Des terres marqu\u00e9es par le conflit\u2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49e3d1c elementor-widget elementor-widget-heading\" data-id=\"49e3d1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AUJOURD\u2019HUI TERRES D\u2019ESPOIR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca8ee5b elementor-widget elementor-widget-text-editor\" data-id=\"ca8ee5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous travaillons avec des communaut\u00e9s indig\u00e8nes, des victimes du conflit arm\u00e9, des producteurs ruraux et des anciens combattants engag\u00e9s dans le processus de paix.<\/p><p>\u00c0 travers le caf\u00e9, ces femmes et ces hommes reconstruisent leur vie, redonnent sens \u00e0 leur territoire, et participent activement \u00e0 la r\u00e9conciliation nationale.<\/p><p>Le caf\u00e9 devient ainsi un moteur de dignit\u00e9 retrouv\u00e9e, d\u2019autonomie et de d\u00e9veloppement local.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70a822c e-con-full e-flex e-con e-parent\" data-id=\"70a822c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ac394cd e-con-full e-flex e-con e-child\" data-id=\"ac394cd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64bdb0f elementor-widget elementor-widget-heading\" data-id=\"64bdb0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une fusion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abee8ec elementor-widget elementor-widget-heading\" data-id=\"abee8ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DES CULTURES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-501a813 elementor-widget elementor-widget-text-editor\" data-id=\"501a813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>U\u2019WA incarne la rencontre entre la Colombie et la France, entre tradition et artisanat, m\u00e9moire et modernit\u00e9.<\/p><p>Du c\u0153ur des terroirs colombiens \u00e0 la tasse, nous ma\u00eetrisons chaque \u00e9tape : de la s\u00e9lection des grains \u00e0 la torr\u00e9faction artisanale, jusqu\u2019au design de nos packagings, fruit de collaborations artistiques entre les deux pays.<\/p><p>Notre univers raconte un dialogue vivant entre racines et renouveau!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b753c0d e-con-full e-flex e-con e-child\" data-id=\"b753c0d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66bb5ba e-con-full e-flex e-con e-parent\" data-id=\"66bb5ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-62c5a45 e-con-full e-flex e-con e-child\" data-id=\"62c5a45\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35d41b1 elementor-widget elementor-widget-heading\" data-id=\"35d41b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une tasse de caf\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f9fe74 elementor-widget elementor-widget-heading\" data-id=\"4f9fe74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">UN ACTE D\u2019ENGAGEMENT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d080e0 elementor-widget elementor-widget-text-editor\" data-id=\"7d080e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Choisir U\u2019WA, c\u2019est soutenir une \u00e9conomie humaine, \u00e9thique et r\u00e9siliente.<\/p><p>C\u2019est partager une tasse qui a le go\u00fbt de la paix, du territoire et de l\u2019espoir. C\u2019est croire qu\u2019un autre mod\u00e8le est possible, respectueux des cultures, des personnes, et de la plan\u00e8te.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f75555 elementor-widget elementor-widget-text-editor\" data-id=\"5f75555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>LA R\u00c9CONCILIATION COMMENCE PAR UNE TASSE DE CAF\u00c9. BIENVENUE CHEZ U\u2019WA !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7aec89 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c7aec89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/nos-cafes\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">NOS CAF\u00c9S<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4888c8 e-con-full e-flex e-con e-parent\" data-id=\"d4888c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-57a900c e-con-full e-flex e-con e-child\" data-id=\"57a900c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8960591 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"8960591\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"650\" height=\"820\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_650x820.jpg\" class=\"attachment-full size-full wp-image-389\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_650x820.jpg 650w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_650x820-300x378.jpg 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_650x820-238x300.jpg 238w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3457c89 e-con-full e-flex e-con e-child\" data-id=\"3457c89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bac134c elementor-widget elementor-widget-image\" data-id=\"bac134c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"400\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_700x400_1.jpg\" class=\"attachment-full size-full wp-image-392\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_700x400_1.jpg 700w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_700x400_1-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b95319c elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"b95319c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"400\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_700x400_2.jpg\" class=\"attachment-full size-full wp-image-395\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_700x400_2.jpg 700w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Nous_700x400_2-300x171.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>QUAND LE CAF\u00c9 A Le go\u00fbt de la paix U\u2019WA est bien plus qu\u2019un caf\u00e9 : c\u2019est un projet de lien, de sens et de transformation ! N\u00e9 de l\u2019union entre la Colombie et la France, notre engagement repose sur une conviction forte : le caf\u00e9 peut \u00eatre un vecteur de changement social, un pont [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-349","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qui Sommes - Nous - UWA Caf\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui Sommes - Nous - UWA Caf\u00e9\" \/>\n<meta property=\"og:description\" content=\"QUAND LE CAF\u00c9 A Le go\u00fbt de la paix U\u2019WA est bien plus qu\u2019un caf\u00e9 : c\u2019est un projet de lien, de sens et de transformation ! N\u00e9 de l\u2019union entre la Colombie et la France, notre engagement repose sur une conviction forte : le caf\u00e9 peut \u00eatre un vecteur de changement social, un pont [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/\" \/>\n<meta property=\"og:site_name\" content=\"UWA Caf\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61569251725677\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T13:20:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"AboutPage\"],\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/\",\"name\":\"Qui Sommes - Nous - UWA Caf\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Flores-2.png\",\"datePublished\":\"2025-07-09T17:09:06+00:00\",\"dateModified\":\"2025-08-05T13:20:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Flores-2.png\",\"contentUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Flores-2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/qui-sommes-nous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui Sommes &#8211; Nous\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"name\":\"U'WA Caf\u00e9\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\",\"name\":\"U'WA Caf\u00e9\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"contentUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"width\":510,\"height\":340,\"caption\":\"U'WA Caf\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61569251725677\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui Sommes - Nous - UWA Caf\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/","og_locale":"fr_FR","og_type":"article","og_title":"Qui Sommes - Nous - UWA Caf\u00e9","og_description":"QUAND LE CAF\u00c9 A Le go\u00fbt de la paix U\u2019WA est bien plus qu\u2019un caf\u00e9 : c\u2019est un projet de lien, de sens et de transformation ! N\u00e9 de l\u2019union entre la Colombie et la France, notre engagement repose sur une conviction forte : le caf\u00e9 peut \u00eatre un vecteur de changement social, un pont [&hellip;]","og_url":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/","og_site_name":"UWA Caf\u00e9","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61569251725677","article_modified_time":"2025-08-05T13:20:21+00:00","og_image":[{"width":1080,"height":750,"url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","AboutPage"],"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/","url":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/","name":"Qui Sommes - Nous - UWA Caf\u00e9","isPartOf":{"@id":"https:\/\/uwa.sapiens-lab.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/#primaryimage"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/#primaryimage"},"thumbnailUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2.png","datePublished":"2025-07-09T17:09:06+00:00","dateModified":"2025-08-05T13:20:21+00:00","breadcrumb":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/#primaryimage","url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2.png","contentUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Flores-2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/uwa.sapiens-lab.com\/fr\/qui-sommes-nous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/uwa.sapiens-lab.com\/fr\/homepage\/"},{"@type":"ListItem","position":2,"name":"Qui Sommes &#8211; Nous"}]},{"@type":"WebSite","@id":"https:\/\/uwa.sapiens-lab.com\/#website","url":"https:\/\/uwa.sapiens-lab.com\/","name":"U'WA Caf\u00e9","description":"","publisher":{"@id":"https:\/\/uwa.sapiens-lab.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uwa.sapiens-lab.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/uwa.sapiens-lab.com\/#organization","name":"U'WA Caf\u00e9","url":"https:\/\/uwa.sapiens-lab.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/","url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","contentUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","width":510,"height":340,"caption":"U'WA Caf\u00e9"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61569251725677"]}]}},"_links":{"self":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages\/349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/comments?post=349"}],"version-history":[{"count":3,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages\/349\/revisions"}],"predecessor-version":[{"id":2911,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages\/349\/revisions\/2911"}],"wp:attachment":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/media?parent=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}