{"id":637,"date":"2025-07-11T10:44:48","date_gmt":"2025-07-11T15:44:48","guid":{"rendered":"https:\/\/uwa.nfvgdigital.com\/politique-de-remboursement\/"},"modified":"2025-07-11T11:12:53","modified_gmt":"2025-07-11T16:12:53","slug":"politique-de-remboursement","status":"publish","type":"page","link":"https:\/\/uwa.sapiens-lab.com\/fr\/politique-de-remboursement\/","title":{"rendered":"Politique de Remboursement"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"637\" class=\"elementor elementor-637 elementor-617\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad3cdfa e-con-full e-flex e-con e-parent\" data-id=\"ad3cdfa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1743df elementor-widget elementor-widget-image\" data-id=\"a1743df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"600\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Politiques.jpg\" class=\"attachment-full size-full wp-image-601\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Politiques.jpg 1920w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Politiques-300x94.jpg 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Politiques-1024x320.jpg 1024w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Politiques-768x240.jpg 768w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Politiques-1536x480.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5770f84 e-con-full e-flex e-con e-parent\" data-id=\"5770f84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f532e8e e-con-full e-flex e-con e-child\" data-id=\"f532e8e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70069fa elementor-widget elementor-widget-heading\" data-id=\"70069fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique de Remboursement<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08468f1 elementor-widget elementor-widget-text-editor\" data-id=\"08468f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Chez U\u2019WA Caf\u00e9, nous attachons une grande importance \u00e0 la qualit\u00e9 de nos produits et \u00e0 la satisfaction de nos clients. Si toutefois vous recevez un paquet endommag\u00e9, nous vous invitons \u00e0 suivre les conditions ci-dessous pour toute demande de remboursement. <\/p><p> <\/p><p><span class=\"font-w-950\">Conditions de remboursement :<\/span><\/p><p>&#8211; Dispones de un plazo m\u00e1ximo de 7 d\u00edas tras la recepci\u00f3n de tu pedido para solicitar un reembolso.<br>&#8211; Le remboursement ne sera accord\u00e9 que si le paquet est ab\u00eem\u00e9 \u00e0 la r\u00e9ception.<br>&#8211; Tout paquet ouvert ou utilis\u00e9 ne pourra faire l\u2019objet d\u2019aucun remboursement.<br>&#8211; Les dommages doivent \u00eatre signal\u00e9s par e-mail \u00e0 l\u2019adresse suivante : contact@uwacafe.com, en joignant des photos du paquet endommag\u00e9, ainsi que le num\u00e9ro de commande concern\u00e9.<\/p><p> <\/p><p><span class=\"font-w-950\">Absence de droit de r\u00e9tractation :<\/span><\/p><p>Conform\u00e9ment \u00e0 l\u2019article L221-28 du Code de la consommation, le droit de r\u00e9tractation ne s\u2019applique pas aux produits alimentaires susceptibles de se d\u00e9t\u00e9riorer rapidement. Nos caf\u00e9s \u00e9tant des denr\u00e9es p\u00e9rissables, aucune r\u00e9tractation n\u2019est possible apr\u00e8s livraison, sauf dans le cas d\u2019un produit endommag\u00e9.<\/p><p> <\/p><p><span class=\"font-w-950\">Traitement des demandes :<\/span><\/p><p>&#8211; Apr\u00e8s r\u00e9ception et v\u00e9rification de votre demande, nous vous confirmerons par retour de mail si celle-ci est \u00e9ligible au remboursement.<br>&#8211; Si votre demande est accept\u00e9e, le remboursement sera effectu\u00e9 sur le moyen de paiement initial dans un d\u00e9lai maximum de 10 jours ouvr\u00e9s.<\/p><p> <\/p><p><span class=\"font-w-950\">Cas non remboursables :<\/span><\/p><p>&#8211; Paquets ouverts ou consomm\u00e9s, m\u00eame partiellement.<br>&#8211; R\u00e9clamations faites au-del\u00e0 de 15 jours apr\u00e8s la r\u00e9ception de la commande.<br>&#8211; Insatisfaction li\u00e9e au go\u00fbt ou \u00e0 la pr\u00e9f\u00e9rence personnelle.<\/p><p> <\/p><p>Pour toute autre question relative \u00e0 votre commande, n\u2019h\u00e9sitez pas \u00e0 nous contacter \u00e0 l\u2019adresse : contact@uwacafe.com<\/p><p> <\/p><p><span class=\"font-w-950\">Merci de votre confiance,<br>L\u2019\u00e9quipe U\u2019WA Caf\u00e9<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de Remboursement Chez U\u2019WA Caf\u00e9, nous attachons une grande importance \u00e0 la qualit\u00e9 de nos produits et \u00e0 la satisfaction de nos clients. Si toutefois vous recevez un paquet endommag\u00e9, nous vous invitons \u00e0 suivre les conditions ci-dessous pour toute demande de remboursement. Conditions de remboursement : &#8211; Dispones de un plazo m\u00e1ximo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-637","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de Remboursement - UWA Caf\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de Remboursement - UWA Caf\u00e9\" \/>\n<meta property=\"og:description\" content=\"Politique de Remboursement Chez U\u2019WA Caf\u00e9, nous attachons une grande importance \u00e0 la qualit\u00e9 de nos produits et \u00e0 la satisfaction de nos clients. Si toutefois vous recevez un paquet endommag\u00e9, nous vous invitons \u00e0 suivre les conditions ci-dessous pour toute demande de remboursement. Conditions de remboursement : &#8211; Dispones de un plazo m\u00e1ximo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/\" \/>\n<meta property=\"og:site_name\" content=\"UWA Caf\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61569251725677\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T16:12:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uwa.nfvgdigital.com\/wp-content\/uploads\/2025\/07\/Politiques.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/\",\"name\":\"Politique de Remboursement - UWA Caf\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uwa.nfvgdigital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Politiques.jpg\",\"datePublished\":\"2025-07-11T15:44:48+00:00\",\"dateModified\":\"2025-07-11T16:12:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uwa.nfvgdigital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Politiques.jpg\",\"contentUrl\":\"https:\\\/\\\/uwa.nfvgdigital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Politiques.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/politica-de-reembolso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de Remboursement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"name\":\"U'WA Caf\u00e9\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\",\"name\":\"U'WA Caf\u00e9\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"contentUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"width\":510,\"height\":340,\"caption\":\"U'WA Caf\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61569251725677\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de Remboursement - UWA Caf\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de Remboursement - UWA Caf\u00e9","og_description":"Politique de Remboursement Chez U\u2019WA Caf\u00e9, nous attachons une grande importance \u00e0 la qualit\u00e9 de nos produits et \u00e0 la satisfaction de nos clients. Si toutefois vous recevez un paquet endommag\u00e9, nous vous invitons \u00e0 suivre les conditions ci-dessous pour toute demande de remboursement. Conditions de remboursement : &#8211; Dispones de un plazo m\u00e1ximo de [&hellip;]","og_url":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/","og_site_name":"UWA Caf\u00e9","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61569251725677","article_modified_time":"2025-07-11T16:12:53+00:00","og_image":[{"url":"https:\/\/uwa.nfvgdigital.com\/wp-content\/uploads\/2025\/07\/Politiques.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/","url":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/","name":"Politique de Remboursement - UWA Caf\u00e9","isPartOf":{"@id":"https:\/\/uwa.sapiens-lab.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/#primaryimage"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/#primaryimage"},"thumbnailUrl":"https:\/\/uwa.nfvgdigital.com\/wp-content\/uploads\/2025\/07\/Politiques.jpg","datePublished":"2025-07-11T15:44:48+00:00","dateModified":"2025-07-11T16:12:53+00:00","breadcrumb":{"@id":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/#primaryimage","url":"https:\/\/uwa.nfvgdigital.com\/wp-content\/uploads\/2025\/07\/Politiques.jpg","contentUrl":"https:\/\/uwa.nfvgdigital.com\/wp-content\/uploads\/2025\/07\/Politiques.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/uwa.sapiens-lab.com\/politica-de-reembolso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/uwa.sapiens-lab.com\/fr\/homepage\/"},{"@type":"ListItem","position":2,"name":"Politique de Remboursement"}]},{"@type":"WebSite","@id":"https:\/\/uwa.sapiens-lab.com\/#website","url":"https:\/\/uwa.sapiens-lab.com\/","name":"U'WA Caf\u00e9","description":"","publisher":{"@id":"https:\/\/uwa.sapiens-lab.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uwa.sapiens-lab.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/uwa.sapiens-lab.com\/#organization","name":"U'WA Caf\u00e9","url":"https:\/\/uwa.sapiens-lab.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/","url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","contentUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","width":510,"height":340,"caption":"U'WA Caf\u00e9"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61569251725677"]}]}},"_links":{"self":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages\/637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/comments?post=637"}],"version-history":[{"count":1,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages\/637\/revisions"}],"predecessor-version":[{"id":638,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/pages\/637\/revisions\/638"}],"wp:attachment":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/media?parent=637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}