{"id":1663,"date":"2025-05-18T17:00:00","date_gmt":"2025-05-18T22:00:00","guid":{"rendered":"https:\/\/uwacafe.com\/le-bulletin-cafeine\/"},"modified":"2025-08-19T03:24:27","modified_gmt":"2025-08-19T08:24:27","slug":"le-bulletin-cafeine","status":"publish","type":"post","link":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/","title":{"rendered":"AU C\u0152UR DE VIOT\u00c1"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1663\" class=\"elementor elementor-1663 elementor-1299\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77c9dfe e-con-full e-flex e-con e-parent\" data-id=\"77c9dfe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93dee35 elementor-widget elementor-widget-heading\" data-id=\"93dee35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Le bulletin<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5ae144 elementor-widget elementor-widget-heading\" data-id=\"c5ae144\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caf\u00e9in\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef97df6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef97df6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bed83e0 e-con-full e-flex e-con e-parent\" data-id=\"bed83e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a19b189 e-con-full e-flex e-con e-child\" data-id=\"a19b189\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d4d4ae elementor-widget elementor-widget-image\" data-id=\"4d4d4ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"550\" height=\"300\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg\" class=\"attachment-full size-full wp-image-1308\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg 550w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1-300x164.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0722223 e-con-full e-flex e-con e-child\" data-id=\"0722223\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a90c132 elementor-widget elementor-widget-image\" data-id=\"a90c132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"270\" height=\"300\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_270x300_2.jpg\" class=\"attachment-full size-full wp-image-1311\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb20f1 elementor-widget elementor-widget-image\" data-id=\"3eb20f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"270\" height=\"300\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_270x300_1.jpg\" class=\"attachment-full size-full wp-image-1314\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3830801 elementor-widget elementor-widget-image\" data-id=\"3830801\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"600\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x600.jpg\" class=\"attachment-full size-full wp-image-1317\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x600.jpg 550w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x600-300x327.jpg 300w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x600-275x300.jpg 275w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-647b45d elementor-widget elementor-widget-image\" data-id=\"647b45d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"300\" src=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_2.jpg\" class=\"attachment-full size-full wp-image-1320\" alt=\"\" srcset=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_2.jpg 550w, https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_2-300x164.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-386bbda e-con-full e-flex e-con e-child\" data-id=\"386bbda\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88a73a5 elementor-widget elementor-widget-text-editor\" data-id=\"88a73a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"font-w-950\">AU C\u0152UR DE VIOT\u00c1 : UNE RENCONTRE AUTOUR DU CAF\u00c9, DE LA PAIX ET DE L\u2019HUMAIN<\/span><\/p><p>Il y a des moments qui donnent tout son sens \u00e0 un projet.<br>Notre visite \u00e0 Viot\u00e1, au c\u0153ur du d\u00e9partement de Cundinamarca, en Colombie, en fait incontestablement partie.<\/p><p>Nous y sommes all\u00e9s apr\u00e8s avoir r\u00e9ceptionn\u00e9, tri\u00e9 et torr\u00e9fi\u00e9 avec soin les \u00e9chantillons de caf\u00e9 de 12 producteurs locaux. Mais l\u2019\u00e9tape la plus importante restait \u00e0 venir : retourner sur leurs terres, les rencontrer, partager avec eux la d\u00e9gustation de leur propre caf\u00e9, fra\u00eechement torr\u00e9fi\u00e9. <\/p><p><span class=\"font-w-950\">UNE RENCONTRE, UNE TRANSMISSION, UN LIEN<\/span><\/p><p>Cette journ\u00e9e fut bien plus qu\u2019un simple retour de r\u00e9sultats.<br>Elle a \u00e9t\u00e9 une rencontre humaine profonde, un moment de partage sinc\u00e8re entre passionn\u00e9s de caf\u00e9.<\/p><p>Nous avons pu mettre en lumi\u00e8re le potentiel exceptionnel de leurs caf\u00e9s, leur offrir des conseils d\u2019am\u00e9lioration, et surtout, leur montrer que leur d\u00e9marche artisanale, \u00e9cologique, sans produits chimiques \u2013 est la voie du caf\u00e9 de sp\u00e9cialit\u00e9.<\/p><p><span class=\"font-w-950\">DES FIRMANTES DE PAZ, CULTIVATEURS D\u2019AVENIR<\/span><\/p><p>Les producteurs que nous avons rencontr\u00e9s sont des firmantes de paz : d\u2019anciens combattants ayant fait le choix courageux de revenir \u00e0 la terre, de reconstruire leur vie par l\u2019agriculture. Leur humilit\u00e9, leur bienveillance, leur volont\u00e9 de bien faire nous ont profond\u00e9ment touch\u00e9s. <\/p><p>Ces hommes et femmes ne sont pas seulement des cultivateurs de caf\u00e9.<br>Ils sont les acteurs d\u2019une Colombie en paix, les gardiens d\u2019un territoire qu\u2019ils soignent, les artisans d\u2019un mod\u00e8le durable, respectueux de la nature et des traditions.<\/p><p><span class=\"font-w-950\">UNE COMMUNAUT\u00c9 UNIE ET INSPIRANTE<\/span><br>Ce jour-l\u00e0, tout le village s\u2019est mobilis\u00e9 pour nous accueillir. En particulier le maire de Viot\u00e1, \u00d3scar Hern\u00e1n Quiroga, dont la pr\u00e9sence et l\u2019enthousiasme ont renforc\u00e9 le sens de cette rencontre.<\/p><p>Un merci tout sp\u00e9cial \u00e0 Luis Enrique, dit Lucho, directeur de l\u2019association des caficulteurs de Viot\u00e1, pour son accueil chaleureux, sa disponibilit\u00e9 et sa profonde gentillesse.<\/p><p><span class=\"font-w-950\">UN MERCI TOUT PARTICULIER<\/span><br>Nous souhaitons remercier du fond du c\u0153ur Antonio Romero, directeur d\u2019Arte y Pasi\u00f3n Caf\u00e9, formateur en torr\u00e9faction et barista.<\/p><p>C\u2019est gr\u00e2ce \u00e0 lui que nous avons pu rencontrer cette communaut\u00e9, vivre cette exp\u00e9rience humaine et sensorielle, et partager cette vision commune d\u2019un caf\u00e9 porteur de sens.<\/p><p><span class=\"font-w-950\">U\u2019WA : QUAND LE CAF\u00c9 A LE GO\u00dbT DE LA PAIX<\/span><br>Ce moment \u00e0 Viot\u00e1 illustre parfaitement ce que nous voulons transmettre \u00e0 travers U\u2019WA : Un caf\u00e9 engag\u00e9, \u00e9quitable, \u00e9coresponsable, qui relie les peuples et r\u00e9concilie les histoires.<\/p><p>Notre ambition est de valoriser ces caf\u00e9s d\u2019exception tout en honorant les mains qui les cultivent.<\/p><p>D\u00e8s la cueillette jusqu\u2019\u00e0 votre tasse, chaque \u00e9tape est un acte d\u2019engagement, de respect et de transmission.<\/p><p><span class=\"font-w-950\">Merci Viot\u00e1. Merci \u00e0 ses producteurs. Merci \u00e0 la paix.  <\/span><br><span class=\"font-w-950\">Et \u00e0 vous, cher\u00b7e\u00b7s lecteur\u00b7trice\u00b7s, bienvenue dans notre univers.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Il y a des moments qui donnent tout son sens \u00e0 un projet.<br \/>\n Notre visite \u00e0 Viot\u00e1, au c\u0153ur du d\u00e9partement de Cundinamarca, en Colombie, en fait incontestablement partie.<\/p>\n","protected":false},"author":1,"featured_media":1308,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-1663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouveautes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Au c\u0153ur de Viot\u00e1 : Rencontre humaine, paix et caf\u00e9 de sp\u00e9cialit\u00e9 en Colombie<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre immersion \u00e0 Viot\u00e1, en Colombie, o\u00f9 U\u2019WA a rencontr\u00e9 des producteurs engag\u00e9s, anciens combattants et artisans d\u2019un caf\u00e9 durable et \u00e9thique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au c\u0153ur de Viot\u00e1 : Rencontre humaine, paix et caf\u00e9 de sp\u00e9cialit\u00e9 en Colombie\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre immersion \u00e0 Viot\u00e1, en Colombie, o\u00f9 U\u2019WA a rencontr\u00e9 des producteurs engag\u00e9s, anciens combattants et artisans d\u2019un caf\u00e9 durable et \u00e9thique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/\" \/>\n<meta property=\"og:site_name\" content=\"UWA Caf\u00e9\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61569251725677\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-18T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T08:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uadminawucffa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"uadminawucffa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/\"},\"author\":{\"name\":\"uadminawucffa\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/person\\\/366066b16ef370c7d303c57d8808e33f\"},\"headline\":\"AU C\u0152UR DE VIOT\u00c1\",\"datePublished\":\"2025-05-18T22:00:00+00:00\",\"dateModified\":\"2025-08-19T08:24:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Bulletin_550x300_1.jpg\",\"articleSection\":[\"Nouveaut\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/\",\"name\":\"Au c\u0153ur de Viot\u00e1 : Rencontre humaine, paix et caf\u00e9 de sp\u00e9cialit\u00e9 en Colombie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Bulletin_550x300_1.jpg\",\"datePublished\":\"2025-05-18T22:00:00+00:00\",\"dateModified\":\"2025-08-19T08:24:27+00:00\",\"description\":\"D\u00e9couvrez notre immersion \u00e0 Viot\u00e1, en Colombie, o\u00f9 U\u2019WA a rencontr\u00e9 des producteurs engag\u00e9s, anciens combattants et artisans d\u2019un caf\u00e9 durable et \u00e9thique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Bulletin_550x300_1.jpg\",\"contentUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Bulletin_550x300_1.jpg\",\"width\":550,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/le-bulletin-cafeine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AU C\u0152UR DE VIOT\u00c1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#website\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"name\":\"U'WA Caf\u00e9\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#organization\",\"name\":\"U'WA Caf\u00e9\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"contentUrl\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-header-510.png\",\"width\":510,\"height\":340,\"caption\":\"U'WA Caf\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61569251725677\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/#\\\/schema\\\/person\\\/366066b16ef370c7d303c57d8808e33f\",\"name\":\"uadminawucffa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09f36f0d2a1e4ad852e603e3238d6e5c9b41e666dbf9ef149a11152fc3199682?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09f36f0d2a1e4ad852e603e3238d6e5c9b41e666dbf9ef149a11152fc3199682?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09f36f0d2a1e4ad852e603e3238d6e5c9b41e666dbf9ef149a11152fc3199682?s=96&d=mm&r=g\",\"caption\":\"uadminawucffa\"},\"sameAs\":[\"https:\\\/\\\/uwa.nfvgdigital.com\"],\"url\":\"https:\\\/\\\/uwa.sapiens-lab.com\\\/fr\\\/author\\\/uadminawucffa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Au c\u0153ur de Viot\u00e1 : Rencontre humaine, paix et caf\u00e9 de sp\u00e9cialit\u00e9 en Colombie","description":"D\u00e9couvrez notre immersion \u00e0 Viot\u00e1, en Colombie, o\u00f9 U\u2019WA a rencontr\u00e9 des producteurs engag\u00e9s, anciens combattants et artisans d\u2019un caf\u00e9 durable et \u00e9thique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/","og_locale":"fr_FR","og_type":"article","og_title":"Au c\u0153ur de Viot\u00e1 : Rencontre humaine, paix et caf\u00e9 de sp\u00e9cialit\u00e9 en Colombie","og_description":"D\u00e9couvrez notre immersion \u00e0 Viot\u00e1, en Colombie, o\u00f9 U\u2019WA a rencontr\u00e9 des producteurs engag\u00e9s, anciens combattants et artisans d\u2019un caf\u00e9 durable et \u00e9thique.","og_url":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/","og_site_name":"UWA Caf\u00e9","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61569251725677","article_published_time":"2025-05-18T22:00:00+00:00","article_modified_time":"2025-08-19T08:24:27+00:00","og_image":[{"width":550,"height":300,"url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg","type":"image\/jpeg"}],"author":"uadminawucffa","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"uadminawucffa","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/#article","isPartOf":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/"},"author":{"name":"uadminawucffa","@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/person\/366066b16ef370c7d303c57d8808e33f"},"headline":"AU C\u0152UR DE VIOT\u00c1","datePublished":"2025-05-18T22:00:00+00:00","dateModified":"2025-08-19T08:24:27+00:00","mainEntityOfPage":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/"},"wordCount":498,"publisher":{"@id":"https:\/\/uwa.sapiens-lab.com\/#organization"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/#primaryimage"},"thumbnailUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg","articleSection":["Nouveaut\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/","url":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/","name":"Au c\u0153ur de Viot\u00e1 : Rencontre humaine, paix et caf\u00e9 de sp\u00e9cialit\u00e9 en Colombie","isPartOf":{"@id":"https:\/\/uwa.sapiens-lab.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/#primaryimage"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/#primaryimage"},"thumbnailUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg","datePublished":"2025-05-18T22:00:00+00:00","dateModified":"2025-08-19T08:24:27+00:00","description":"D\u00e9couvrez notre immersion \u00e0 Viot\u00e1, en Colombie, o\u00f9 U\u2019WA a rencontr\u00e9 des producteurs engag\u00e9s, anciens combattants et artisans d\u2019un caf\u00e9 durable et \u00e9thique.","breadcrumb":{"@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/#primaryimage","url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg","contentUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/Bulletin_550x300_1.jpg","width":550,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/uwa.sapiens-lab.com\/fr\/le-bulletin-cafeine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/uwa.sapiens-lab.com\/fr\/homepage\/"},{"@type":"ListItem","position":2,"name":"AU C\u0152UR DE VIOT\u00c1"}]},{"@type":"WebSite","@id":"https:\/\/uwa.sapiens-lab.com\/#website","url":"https:\/\/uwa.sapiens-lab.com\/","name":"U'WA Caf\u00e9","description":"","publisher":{"@id":"https:\/\/uwa.sapiens-lab.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uwa.sapiens-lab.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/uwa.sapiens-lab.com\/#organization","name":"U'WA Caf\u00e9","url":"https:\/\/uwa.sapiens-lab.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/","url":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","contentUrl":"https:\/\/uwa.sapiens-lab.com\/wp-content\/uploads\/2025\/07\/logo-header-510.png","width":510,"height":340,"caption":"U'WA Caf\u00e9"},"image":{"@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61569251725677"]},{"@type":"Person","@id":"https:\/\/uwa.sapiens-lab.com\/#\/schema\/person\/366066b16ef370c7d303c57d8808e33f","name":"uadminawucffa","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/09f36f0d2a1e4ad852e603e3238d6e5c9b41e666dbf9ef149a11152fc3199682?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09f36f0d2a1e4ad852e603e3238d6e5c9b41e666dbf9ef149a11152fc3199682?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09f36f0d2a1e4ad852e603e3238d6e5c9b41e666dbf9ef149a11152fc3199682?s=96&d=mm&r=g","caption":"uadminawucffa"},"sameAs":["https:\/\/uwa.nfvgdigital.com"],"url":"https:\/\/uwa.sapiens-lab.com\/fr\/author\/uadminawucffa\/"}]}},"_links":{"self":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/posts\/1663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/comments?post=1663"}],"version-history":[{"count":3,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/posts\/1663\/revisions"}],"predecessor-version":[{"id":2940,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/posts\/1663\/revisions\/2940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/media\/1308"}],"wp:attachment":[{"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/media?parent=1663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/categories?post=1663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uwa.sapiens-lab.com\/fr\/wp-json\/wp\/v2\/tags?post=1663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}